{"id":180571,"date":"2023-02-14T15:54:48","date_gmt":"2023-02-14T14:54:48","guid":{"rendered":"https:\/\/kinedo-bad.de\/produits\/douches-completes\/kineprime-glass\/"},"modified":"2026-01-21T17:14:13","modified_gmt":"2026-01-21T16:14:13","slug":"kineprime-glass","status":"publish","type":"page","link":"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/kineprime-glass\/","title":{"rendered":"Kineprime Glass"},"content":{"rendered":"<div class=\"m-page-hero small reverse\">\n  <div class=\"m-page-hero__background\">\n                      <picture class=\"rocket-no-lazy m-page-hero__background-img\">\n          <source media=\"(min-width: 105em)\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kineprime_glass_nischenausfuehrung_mechanische_mischbatterie_drehtuer_100x80.jpg 2000w,\n                        https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kineprime_glass_nischenausfuehrung_mechanische_mischbatterie_drehtuer_100x80-1500x643.jpg 1500w,\n                        https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kineprime_glass_nischenausfuehrung_mechanische_mischbatterie_drehtuer_100x80-1000x429.jpg 1000w,\n                        https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kineprime_glass_nischenausfuehrung_mechanische_mischbatterie_drehtuer_100x80-500x214.jpg 500w,\n                        https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kineprime_glass_nischenausfuehrung_mechanische_mischbatterie_drehtuer_100x80-250x107.jpg 250w\">\n          <source srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinedo_kineglass_prime.jpg 2000w,\n                        https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinedo_kineglass_prime-1500x844.jpg 1500w,\n                        https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinedo_kineglass_prime-1000x562.jpg 1000w,\n                        https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinedo_kineglass_prime-500x281.jpg 500w,\n                        https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinedo_kineglass_prime-250x141.jpg 250w\">\n          <img decoding=\"async\" class=\"rocket-no-lazy\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinedo_kineglass_prime-1500x844.jpg\" alt=\"\">\n        <\/picture>\n            <\/div>\n\n  <div class=\"m-page-hero__content-wrapper\">\n    <div class=\"m-page-hero__content\">\n      <div class=\"wrapper\">\n        \n        \n                    <h1 class=\"m-page-hero__content-title right\" data-count=\"16\" data-text-align=\"\"\"\">\n            Kineprime Glass           <\/h1>\n\n        \n        <div class=\"m-page-hero__content-text\">\n                      <p>\n              Les cabines de douche Kineprime Glass conf\u00e8rent \u00e0 la salle de bains un confort haut de gamme.             <\/p>\n          \n\n\n          \n\n            \n\n\n                  <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/div>\n\n<section class=\"m-breadcrumb\">\n  <div class=\"wrapper\">\n    <div id=\"breadcrumbs\" class=\"m-breadcrumb__list\"><span><span><a href=\"https:\/\/kinedo-bad.de\/fr\/\">Start<\/a><\/span><\/span><\/div>  <\/div>\n<\/section>\n\n\n<div class=\"modul-raster-wrapper normal\" >\n  <div class=\"wrapper\">\n    <div class=\"modul-raster  spacing-top--medium spacing-bottom--medium\">\n              <div class=\"row  wrap\">\n                                                  <div class=\"raster-block rastercolumn col-5 \n                \">\n\n                \n                  \n                      <div class=\"textblock\">\n\n                      \n                      <div class=\"wysiwyg\">\n                        <h3 class=\"grey\">Avec Kineprime Glass, se doucher devient l&#8217;activit\u00e9 prime-time \u2013 et ce, n&#8217;importe quand.<\/h3>\n<p>Les cabines de douche compl\u00e8tes de la gamme Kineprime sont aussi simples que pratiques au quotidien. Ces douches compl\u00e8tes Kineprime Glass, dont le r\u00f4le est de vous procurer jour apr\u00e8s jour le plaisir de la douche, remplissent leurs fonctions dans le calme et \u00e0 un niveau haut de gamme extr\u00eamement fiable.<\/p>\n<p>Les cabines de douche enti\u00e8rement \u00e9quip\u00e9es convainquent par leur design simple, leur traitement de grande qualit\u00e9 et leurs mat\u00e9riaux robustes, pour vous offrir l\u2019exp\u00e9rience d\u2019une douche source de plaisir, jour apr\u00e8s jour.<\/p>\n                      <\/div>\n                      <\/div>\n                    \n                        <\/div>\n                                                  <div class=\"raster-block rastercolumn col-1 \n                \">\n\n                \n\n                    \n                        <\/div>\n                                                  <div class=\"raster-block rastercolumn col-5 \n                \">\n\n                                                                                        <div class=\"bildblock\" style=\"\n                    --max-width: 100%;\n                    --text-align: left;\n                    \">\n                                        \n                                              <div class=\"img-wrapper\" data-inview>\n\n                                                    <img decoding=\"async\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinedo_kineglass_prime.jpg 2500w,\n                                  https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinedo_kineglass_prime-1500x844.jpg 1500w,\n                                  https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinedo_kineglass_prime-1000x562.jpg 1000w,\n                                  https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinedo_kineglass_prime-500x281.jpg 500w,\n                                  https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinedo_kineglass_prime-250x141.jpg 250w\" sizes=\"(min-width: 56em) 1500px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinedo_kineglass_prime-1000x562.jpg\" alt=\"\" itemprob=\"image\"  data-img-popup=\"\" href=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinedo_kineglass_prime.jpg\" >\n                        <\/div>\n\n                        \n                    \n                    \n\n                                      <\/div>\n\n                \n                        <\/div>\n                                                  <div class=\"raster-block rastercolumn col-1 \n                \">\n\n                \n\n                    \n                        <\/div>\n                                                              <\/div>\n                                <\/div>\n        <\/div>\n    <\/div>\n\n\n<section class=\"m-full-image-slider  spacing-top--none spacing-bottom--medium\" id=\"Galerie\">\n\n  <div class=\"m-full-image-slider__wrapper\">\n    <div class=\"m-full-image-slider__arrows\">\n      <button class=\"m-full-image-slider__arrow prev\" data-gallery-full-slider-prev=\"\">\n      <\/button>\n      <button class=\"m-full-image-slider__arrow next\" data-gallery-full-slider-next=\"\">\n      <\/button>\n    <\/div>\n    <div data-gallery-full-slider=\"\">\n      \n                          \n            \n\n  <div class=\"m-full-image-slider__slide\">\n    <div class=\"img-wrapper\">\n            <div>\n        <div class=\"img-wrapper\" data-bild=\"\/wp-content\/medien\/knmi_kineprime_glass_eckausfuehrung_schiebetueren_thermostat_100x80.jpg\">\n          <img decoding=\"async\" data-lazy=\"\/wp-content\/medien\/knmi_kineprime_glass_eckausfuehrung_schiebetueren_thermostat_100x80.jpg\" src=\"\/wp-content\/medien\/large\/knmi_kineprime_glass_eckausfuehrung_schiebetueren_thermostat_100x80.webp\" alt=\"knmi_kineprime_glass_eckausfuehrung_schiebetueren_thermostat_100x80.jpg\" data-bild=\"\/wp-content\/medien\/knmi_kineprime_glass_eckausfuehrung_schiebetueren_thermostat_100x80.jpg\" data-ursprung=\"\/wp-content\/medien\/large\/knmi_kineprime_glass_eckausfuehrung_schiebetueren_thermostat_100x80.webp\" srcset=\"\/wp-content\/medien\/medium\/knmi_kineprime_glass_eckausfuehrung_schiebetueren_thermostat_100x80.webp 250w, \/wp-content\/medien\/large\/knmi_kineprime_glass_eckausfuehrung_schiebetueren_thermostat_100x80.webp 500w, \/wp-content\/medien\/knmi_kineprime_glass_eckausfuehrung_schiebetueren_thermostat_100x80.jpg 1000w, \/wp-content\/medien\/knmi_kineprime_glass_eckausfuehrung_schiebetueren_thermostat_100x80.jpg 2000w\">\n        <\/div>\n      <\/div>\n    <\/div>\n    <div class=\"wrapper\">\n      <div class=\"m-full-image-slider__untertitel\">\n        <div class=\"m-full-image-slider_title\">\n          <h3>Kineprime Glass, ex\u00e9cution d&#8217;angle<\/h3>\n        <\/div>\n        <div class=\"wysiwyg\">\n          Kineprime Glass, ex\u00e9cution d&#8217;angle, est une douche enti\u00e8rement \u00e9quip\u00e9e d\u2019un bac de douche, de cloisons et de robinetteries assortis dans un design simple. Qu\u2019elle soit dot\u00e9e d\u2019une porte battante ou de deux portes coulissantes, Kineprime Glass permet un acc\u00e8s ais\u00e9 \u00e0 la douche et un gain de place dans la salle de bains.<br \/>\r\n<br \/>\r\nGr\u00e2ce \u00e0 ses profil\u00e9s blanc mat et \u00e0 son design r\u00e9duit, Kineprime Glass peut \u00eatre combin\u00e9 avec diff\u00e9rents styles d\u2019am\u00e9nagement et ce, en restant discr\u00e8tement \u00e0 l\u2019arri\u00e8re-plan.<br \/>\r\n<br \/>\r\nLa fonctionnalit\u00e9 n&#8217;a pas \u00e9t\u00e9 n\u00e9glig\u00e9e pour autant\u00a0!        <\/div>\n\n      <\/div>\n    <\/div>\n  <\/div>\n\n          \n            \n\n  <div class=\"m-full-image-slider__slide\">\n    <div class=\"img-wrapper\">\n            <div>\n        <div class=\"img-wrapper\" data-bild=\"\/wp-content\/medien\/knmi_kineprime_glass_nischenausfuehrung_schwenktuer_mechanische_mischbatterie_100x80.jpg\">\n          <img decoding=\"async\" data-lazy=\"\/wp-content\/medien\/knmi_kineprime_glass_nischenausfuehrung_schwenktuer_mechanische_mischbatterie_100x80.jpg\" src=\"\/wp-content\/medien\/large\/knmi_kineprime_glass_nischenausfuehrung_schwenktuer_mechanische_mischbatterie_100x80.webp\" alt=\"knmi_kineprime_glass_nischenausfuehrung_schwenktuer_mechanische_mischbatterie_100x80.jpg\" data-bild=\"\/wp-content\/medien\/knmi_kineprime_glass_nischenausfuehrung_schwenktuer_mechanische_mischbatterie_100x80.jpg\" data-ursprung=\"\/wp-content\/medien\/large\/knmi_kineprime_glass_nischenausfuehrung_schwenktuer_mechanische_mischbatterie_100x80.webp\" srcset=\"\/wp-content\/medien\/medium\/knmi_kineprime_glass_nischenausfuehrung_schwenktuer_mechanische_mischbatterie_100x80.webp 250w, \/wp-content\/medien\/large\/knmi_kineprime_glass_nischenausfuehrung_schwenktuer_mechanische_mischbatterie_100x80.webp 500w, \/wp-content\/medien\/knmi_kineprime_glass_nischenausfuehrung_schwenktuer_mechanische_mischbatterie_100x80.jpg 1000w, \/wp-content\/medien\/knmi_kineprime_glass_nischenausfuehrung_schwenktuer_mechanische_mischbatterie_100x80.jpg 2000w\">\n        <\/div>\n      <\/div>\n    <\/div>\n    <div class=\"wrapper\">\n      <div class=\"m-full-image-slider__untertitel\">\n        <div class=\"m-full-image-slider_title\">\n          <h3>Kineprime Glass, ex\u00e9cution en niche<\/h3>\n        <\/div>\n        <div class=\"wysiwyg\">\n          Kineprime Glass, ex\u00e9cution en niche, est une douche enti\u00e8rement \u00e9quip\u00e9e d\u2019un bac de douche, de cloisons et de robinetteries assortis dans un design simple. La porte battante permet un acc\u00e8s ais\u00e9 \u00e0 la douche et un gain de place dans la salle de bains.<br \/>\r\n<br \/>\r\nGr\u00e2ce \u00e0 ses profil\u00e9s blanc mat et \u00e0 son design r\u00e9duit, Kineprime Glass peut \u00eatre combin\u00e9 avec diff\u00e9rents styles d\u2019am\u00e9nagement et ce, en restant discr\u00e8tement \u00e0 l\u2019arri\u00e8re-plan.<br \/>\r\n<br \/>\r\nLa fonctionnalit\u00e9 n&#8217;a pas \u00e9t\u00e9 n\u00e9glig\u00e9e pour autant\u00a0!        <\/div>\n\n      <\/div>\n    <\/div>\n  <\/div>\n\n                            <\/div>\n  <\/div>\n\n<\/section>\n\n<section class=\"m-tile-list m-tile-list--1-2 spacing-top--none spacing-bottom--medium\" id=\"Produkte\">\n  <div class=\"wrapper\">\n    <div class=\"m-tile-list__title with-text\">\n      <h2 class=\"\">\n        It&#8217;s Prime-Time! Mais quel mod\u00e8le Kineprime Glass allez-vous choisir\u00a0?      <\/h2>\n\n              <div>\n          <aside class=\"wysiwyg\">\n            <p>Avec leur design simple, les deux mod\u00e8les de la s\u00e9rie Kineprime Glass s\u2019int\u00e8grent sans probl\u00e8me dans tout environnement de salle de bains. <br \/>\r\n<br \/>\r\nAvec une porte battante ou deux portes coulissantes, avec Kineprime Glass choisissez une cabine de douche compl\u00e8te de belle forme et extr\u00eamement pratique.<\/p>\n          <\/aside>\n        <\/div>\n          <\/div>\n\n    <div class=\"m-tile-list__list\">\n                <a class=\"m-tile\" href=\"https:\/\/kinedo-bad.de\/fr\/produkt\/kineprime-glass-execution-dangle\/\" aria-label=\"Kineprime Glass, ex\u00e9cution d&#8217;angle\" product-id=\"180676\">\n            <div class=\"m-tile__content\">\n              <div class=\"m-tile__background\">\n                                                \n\n                                                    <img decoding=\"async\"\n                    srcset=\"\/wp-content\/medien\/extralarge\/knmi_kineprime_glass_eckausfuehrung_schiebetueren_thermostat_100x80.webp 1200w, \/wp-content\/medien\/large\/knmi_kineprime_glass_eckausfuehrung_schiebetueren_thermostat_100x80.webp 800w, \/wp-content\/medien\/large\/knmi_kineprime_glass_eckausfuehrung_schiebetueren_thermostat_100x80.webp 500w, \/wp-content\/medien\/small\/knmi_kineprime_glass_eckausfuehrung_schiebetueren_thermostat_100x80.webp 200w\"\n                    sizes=\"(min-width: 56em) 900px, 100vw\"\n                    src=\"\/wp-content\/medien\/small\/knmi_kineprime_glass_eckausfuehrung_schiebetueren_thermostat_100x80.webp\"\n                    alt=\"Kineprime Glass, ex\u00e9cution d&#8217;angle\"\n                    width=\"600\"\n                    height=\"338\"\n                    itemprop=\"image\">\n                              <\/div>\n\n              <div class=\"m-tile__title\">\n                <span class=\"m-tile__title-name\">\n                  Kineprime Glass, ex\u00e9cution d&#8217;angle                <\/span>\n\n\n                <span class=\"m-tile__title-more\">\n                  plus                <\/span>\n              <\/div>\n            <\/div>\n\n                          <div class=\"m-tile__text\">\n                Cabine de douche compl\u00e8te pratique au design simple de forme carr\u00e9e avec portes battantes ou coulissantes              <\/div>\n                      <\/a>          <a class=\"m-tile\" href=\"https:\/\/kinedo-bad.de\/fr\/produkt\/kineprime-glass-version-en-niche\/\" aria-label=\"Kineprime Glass, ex\u00e9cution en niche\" product-id=\"180675\">\n            <div class=\"m-tile__content\">\n              <div class=\"m-tile__background\">\n                                                \n\n                                                    <img decoding=\"async\"\n                    srcset=\"\/wp-content\/medien\/extralarge\/knmi_kineprime_glass_nischenausfuehrung_schwenktuer_mechanische_mischbatterie_100x80.webp 1200w, \/wp-content\/medien\/large\/knmi_kineprime_glass_nischenausfuehrung_schwenktuer_mechanische_mischbatterie_100x80.webp 800w, \/wp-content\/medien\/large\/knmi_kineprime_glass_nischenausfuehrung_schwenktuer_mechanische_mischbatterie_100x80.webp 500w, \/wp-content\/medien\/small\/knmi_kineprime_glass_nischenausfuehrung_schwenktuer_mechanische_mischbatterie_100x80.webp 200w\"\n                    sizes=\"(min-width: 56em) 900px, 100vw\"\n                    src=\"\/wp-content\/medien\/small\/knmi_kineprime_glass_nischenausfuehrung_schwenktuer_mechanische_mischbatterie_100x80.webp\"\n                    alt=\"Kineprime Glass, ex\u00e9cution en niche\"\n                    width=\"600\"\n                    height=\"338\"\n                    itemprop=\"image\">\n                              <\/div>\n\n              <div class=\"m-tile__title\">\n                <span class=\"m-tile__title-name\">\n                  Kineprime Glass, ex\u00e9cution en niche                <\/span>\n\n\n                <span class=\"m-tile__title-more\">\n                  plus                <\/span>\n              <\/div>\n            <\/div>\n\n                          <div class=\"m-tile__text\">\n                Cabine de douche compl\u00e8te pratique au design simple, de forme carr\u00e9e avec porte battante              <\/div>\n                      <\/a>    <\/div>\n  <\/div>\n<\/section>\n\n\n<section class=\"m-image-text-disturber reverse  spacing-top--none spacing-bottom--none textsizebig\">\n      <div class=\"m-image-text-disturber__background \">\n\n          <div class=\"img-wrapper\">\n                  \n          <style>\n            \/* Standardgr\u00f6\u00dfe f\u00fcr gro\u00dfe Bildschirme *\/\n            #my-image-6a97ae7c39737 {\n              background-image: url('https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kineprime_glass_nischenausfuehrung_mechanische_mischbatterie_drehtuer_100x80.jpg');\n              background-position: 69.6% 42.99%;\n              background-size: cover;\n              height: 100%;\n              width: 100%;\n              position: absolute;\n            }\n\n\n            \/* Gr\u00f6\u00dfere Bildschirme *\/\n            @media (max-width: 1200px) {\n              #my-image-6a97ae7c39737 {\n                background-image: url('https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kineprime_glass_nischenausfuehrung_mechanische_mischbatterie_drehtuer_100x80-1500x643.jpg');\n                background-position: 69.6% 42.99%;\n                \/* Gleiche Positionierung *\/\n              }\n            }\n\n            \/* Mittlere Bildschirme *\/\n            @media (max-width: 768px) {\n              #my-image-6a97ae7c39737 {\n                background-image: url('https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kineprime_glass_nischenausfuehrung_mechanische_mischbatterie_drehtuer_100x80-1500x643.jpg');\n                background-position: 69.6% 42.99%;\n                \/* Gleiche Positionierung *\/\n              }\n            }\n\n            \/* Kleine Bildschirme *\/\n            @media (max-width: 480px) {\n              #my-image-6a97ae7c39737 {\n                background-image: url('https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kineprime_glass_nischenausfuehrung_mechanische_mischbatterie_drehtuer_100x80-1500x643.jpg');\n                background-position: 69.6% 42.99%;\n                \/* Gleiche Positionierung *\/\n              }\n            }\n          <\/style>\n\n          <div id=\"my-image-6a97ae7c39737\"><\/div>\n\n\n        \n      <\/div>\n\n      \n    \n\n  <\/div>\n\n  <div class=\"m-image-text-disturber__content-wrapper\">\n    <div class=\"m-image-text-disturber__content\">\n              <h2 class=\"m-image-text-disturber__title\">\n          Douche compl\u00e8te au design simple        <\/h2>\n      \n      \n\n      <div class=\"wysiwyg\">\n        <ul>\n<li>Disponible en version carr\u00e9e ou arrondie et en diff\u00e9rentes dimensions<\/li>\n<li>Au choix avec une porte battante ou des portes coulissantes<\/li>\n<li>Verre transparent<\/li>\n<li>Parois arri\u00e8re en verre de s\u00e9curit\u00e9 blanc<\/li>\n<li>Robinetterie de douche compl\u00e8te, y compris douchette<\/li>\n<li>Bac de douche antid\u00e9rapant en Biocryl, avec \u00e9vacuation et grille d&#8217;\u00e9vacuation en acier inoxydable<\/li>\n<\/ul>\n      <\/div>\n\n            \n      \n    <\/div>\n  <\/div>\n<\/section>\n\n\n<div class=\"modul-raster-wrapper normal\" >\n  <div class=\"wrapper\">\n    <div class=\"modul-raster  spacing-top--medium spacing-bottom--small\">\n              <div class=\"row  wrap\">\n                                                  <div class=\"raster-block rastercolumn col-1 \n                \">\n\n                \n\n                    \n                        <\/div>\n                                                  <div class=\"raster-block rastercolumn col-4 \n                \">\n\n                \n                  \n                      <div class=\"textblock\">\n\n                      \n                      <div class=\"wysiwyg\">\n                        <p><span class=\"headlinesubtext\">D\u00e9tails du produit<\/span><\/p>\n<h3 class=\"grey\">Kineprime Glass, version d&#8217;angle<\/h3>\n<ol>\n<li>Douchette \u00e0 main avec jets r\u00e9glables<\/li>\n<li>Mitigeur thermostatique<\/li>\n<\/ol>\n                      <\/div>\n                      <\/div>\n                    \n                        <\/div>\n                                                  <div class=\"raster-block rastercolumn col-1 \n                \">\n\n                \n\n                    \n                        <\/div>\n                                                  <div class=\"raster-block rastercolumn col-5 \n                raster-block-slick\">\n\n                                      \n                      \n                        <div class=\"m-gallery m-gallery--2\">\n                                                      <figure>\n                              <img srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knw_kineprime_glass_thermostat_1500x1500-250x253.jpg 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knw_kineprime_glass_thermostat_1500x1500-500x506.jpg 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knw_kineprime_glass_thermostat_1500x1500-1000x1012.jpg 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knw_kineprime_glass_thermostat_1500x1500-1500x1518.jpg 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knw_kineprime_glass_thermostat_1500x1500.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knw_kineprime_glass_thermostat_1500x1500-1000x1012.jpg\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"2964\" height=\"3000\" data-img-popup=\"\" href=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knw_kineprime_glass_thermostat_1500x1500.jpg\">\n                            <\/figure>\n                                                      <figure>\n                              <img srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knw_kineprime_glass_handbrause_1500x1500-250x250.webp 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knw_kineprime_glass_handbrause_1500x1500-500x500.webp 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knw_kineprime_glass_handbrause_1500x1500-1000x1000.webp 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knw_kineprime_glass_handbrause_1500x1500.webp 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knw_kineprime_glass_handbrause_1500x1500.webp 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knw_kineprime_glass_handbrause_1500x1500-1000x1000.webp\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"1250\" height=\"1250\" data-img-popup=\"\" href=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knw_kineprime_glass_handbrause_1500x1500.webp\">\n                            <\/figure>\n                                                  <\/div>\n\n                      \n                    \n                        <\/div>\n                                                  <div class=\"raster-block rastercolumn col-1 \n                \">\n\n                \n\n                    \n                        <\/div>\n                                                              <\/div>\n                                <\/div>\n        <\/div>\n    <\/div>\n\n<section class=\"m-product-color-accordion  spacing-top--medium spacing-bottom--none\">\n  <div class=\"wrapper\">\n    <div class=\"m-product-color-accordion__row-wrapper\">\n      <div class=\"m-product-color-accordion__row open\" data-accordion=\"\">\n        <div class=\"m-product-color-accordion__title\" data-accordion-trigger=\"\">\n          Ex\u00e9cutions, Couleurs, Mat\u00e9riaux, Caract\u00e9ristiques\n        <\/div>\n        <div class=\"m-product-color-accordion__content\">\n\n                                              <div class=\"m-product-color-accordion__content-row\" data-name=\"Ex\u00e9cutions\">\n                <div class=\"m-product-color-accordion__content-name\">\n                  Ex\u00e9cutions                <\/div>\n\n\n\n                <div class=\"m-product-color-accordion__content-data\">\n                  <ul class=\"m-square-list\">\n                                            <li class=\"m-square-list__item \"\n                          >\n                                                      <img  data-popup-src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knw-eckausfuehrung.svg\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knw-eckausfuehrung.svg\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\">\n                                                                              <span title=\"Ex\u00e9cution d&#039;angle\">\n                            Ex\u00e9cution d&#039;angle                          <\/span>\n                        <\/li>\n                                      <\/ul>\n                <\/div>\n              <\/div>\n                                                <div class=\"m-product-color-accordion__content-row\" data-name=\"Couleurs\">\n                <div class=\"m-product-color-accordion__content-name\">\n                  Couleurs                <\/div>\n\n\n\n                <div class=\"m-product-color-accordion__content-data\">\n                  <ul class=\"m-square-list\">\n                                            <li class=\"m-square-list__item m-img-magnifier-glass\"\n                          data-productname=\"Kineprime Glass, ex\u00e9cution d&#8217;angle\">\n                                                      <img data-magnify=\"\" data-glass-img=\"\/wp-content\/medien\/large\/knw_weiss.webp\" data-popup-src=\"\/wp-content\/medien\/knw_weiss.jpg\" srcset=\"\/wp-content\/medien\/small\/knw_weiss.webp 250w, \/wp-content\/medien\/medium\/knw_weiss.webp 500w, \/wp-content\/medien\/large\/knw_weiss.webp 1000w, \/wp-content\/medien\/knw_weiss.jpg 1500w, \/wp-content\/medien\/knw_weiss.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"\/wp-content\/medien\/large\/knw_weiss.webp\" alt=\"knw_weiss.jpg\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"2250\">\n                                                                              <span title=\"blanc (mat)\">\n                            blanc (mat)                          <\/span>\n                        <\/li>\n                                      <\/ul>\n                <\/div>\n              <\/div>\n                                                <div class=\"m-product-color-accordion__content-row\" data-name=\"Mat\u00e9riel\">\n                <div class=\"m-product-color-accordion__content-name\">\n                  Mat\u00e9riaux                <\/div>\n\n\n\n                <div class=\"m-product-color-accordion__content-data\">\n                  <ul class=\"m-square-list\">\n                                            <li class=\"m-square-list__item m-img-magnifier-glass\"\n                          data-productname=\"Kineprime Glass, ex\u00e9cution d&#8217;angle\">\n                                                      <img data-magnify=\"\" data-glass-img=\"\/wp-content\/medien\/large\/knw_weiss.webp\" data-popup-src=\"\/wp-content\/medien\/knw_weiss.jpg\" srcset=\"\/wp-content\/medien\/small\/knw_weiss.webp 250w, \/wp-content\/medien\/medium\/knw_weiss.webp 500w, \/wp-content\/medien\/large\/knw_weiss.webp 1000w, \/wp-content\/medien\/knw_weiss.jpg 1500w, \/wp-content\/medien\/knw_weiss.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"\/wp-content\/medien\/large\/knw_weiss.webp\" alt=\"knw_weiss.jpg\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"2250\">\n                                                                              <span title=\"Aluminium, blanc rev\u00eatu par poudre\">\n                            Aluminium, blanc rev\u00eatu par poudre                          <\/span>\n                        <\/li>\n                                      <\/ul>\n                <\/div>\n              <\/div>\n                                                <div class=\"m-product-color-accordion__content-row\" data-name=\"Mat\u00e9riau verre\">\n                <div class=\"m-product-color-accordion__content-name\">\n                  Mat\u00e9riau verre                <\/div>\n\n\n\n                <div class=\"m-product-color-accordion__content-data\">\n                  <ul class=\"m-square-list\">\n                                            <li class=\"m-square-list__item m-img-magnifier-glass\"\n                          data-productname=\"Kineprime Glass, ex\u00e9cution d&#8217;angle\">\n                                                      <img data-magnify=\"\" data-glass-img=\"\/wp-content\/medien\/large\/knw_klarglas.webp\" data-popup-src=\"\/wp-content\/medien\/knw_klarglas.jpg\" srcset=\"\/wp-content\/medien\/small\/knw_klarglas.webp 250w, \/wp-content\/medien\/medium\/knw_klarglas.webp 500w, \/wp-content\/medien\/large\/knw_klarglas.webp 1000w, \/wp-content\/medien\/knw_klarglas.jpg 1500w, \/wp-content\/medien\/knw_klarglas.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"\/wp-content\/medien\/large\/knw_klarglas.webp\" alt=\"knw_klarglas.jpg\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"1042\" height=\"1042\">\n                                                                              <span title=\"Verre transparent\">\n                            Verre transparent                          <\/span>\n                        <\/li>\n                                      <\/ul>\n                <\/div>\n              <\/div>\n                                                <div class=\"m-product-color-accordion__content-row\" data-name=\"Mat\u00e9riau de l&#039;armature\">\n                <div class=\"m-product-color-accordion__content-name\">\n                  Mat\u00e9riau de l&#039;armature                <\/div>\n\n\n\n                <div class=\"m-product-color-accordion__content-data\">\n                  <ul class=\"m-square-list\">\n                                            <li class=\"m-square-list__item m-img-magnifier-glass\"\n                          data-productname=\"Kineprime Glass, ex\u00e9cution d&#8217;angle\">\n                                                      <img data-magnify=\"\" data-glass-img=\"\/wp-content\/medien\/large\/knw_weiss.webp\" data-popup-src=\"\/wp-content\/medien\/knw_weiss.jpg\" srcset=\"\/wp-content\/medien\/small\/knw_weiss.webp 250w, \/wp-content\/medien\/medium\/knw_weiss.webp 500w, \/wp-content\/medien\/large\/knw_weiss.webp 1000w, \/wp-content\/medien\/knw_weiss.jpg 1500w, \/wp-content\/medien\/knw_weiss.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"\/wp-content\/medien\/large\/knw_weiss.webp\" alt=\"knw_weiss.jpg\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"2250\">\n                                                                              <span title=\"Verre de s\u00e9curit\u00e9, blanc\">\n                            Verre de s\u00e9curit\u00e9, blanc                          <\/span>\n                        <\/li>\n                                      <\/ul>\n                <\/div>\n              <\/div>\n                                                <div class=\"m-product-color-accordion__content-row\" data-name=\"Receveur de douche\">\n                <div class=\"m-product-color-accordion__content-name\">\n                  Receveur de douche                <\/div>\n\n\n\n                <div class=\"m-product-color-accordion__content-data\">\n                  <ul class=\"m-square-list\">\n                                            <li class=\"m-square-list__item m-img-magnifier-glass\"\n                          data-productname=\"Kineprime Glass, ex\u00e9cution d&#8217;angle\">\n                                                      <img data-magnify=\"\" data-glass-img=\"\/wp-content\/medien\/large\/knw_biocryl_und_biotec.webp\" data-popup-src=\"\/wp-content\/medien\/knw_biocryl_und_biotec.jpg\" srcset=\"\/wp-content\/medien\/small\/knw_biocryl_und_biotec.webp 250w, \/wp-content\/medien\/medium\/knw_biocryl_und_biotec.webp 500w, \/wp-content\/medien\/large\/knw_biocryl_und_biotec.webp 1000w, \/wp-content\/medien\/knw_biocryl_und_biotec.jpg 1500w, \/wp-content\/medien\/knw_biocryl_und_biotec.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"\/wp-content\/medien\/large\/knw_biocryl_und_biotec.webp\" alt=\"knw_biocryl_und_biotec.jpg\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\">\n                                                                              <span title=\"Biocryl + Biotec\">\n                            Biocryl + Biotec                          <\/span>\n                        <\/li>\n                                      <\/ul>\n                <\/div>\n              <\/div>\n                                                <div class=\"m-product-color-accordion__content-row\" data-name=\"caract\u00e9ristiques\">\n                <div class=\"m-product-color-accordion__content-name\">\n                  Caract\u00e9ristiques                <\/div>\n\n\n\n                <div class=\"m-product-color-accordion__content-data\">\n                  <ul class=\"m-square-list\">\n                                            <li class=\"m-square-list__item \"\n                          >\n                                                      <img data-magnify=\"\" data-glass-img=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Kalkschutz-1.png\" data-popup-src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Kalkschutz-1.png\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Kalkschutz-1-250x250.png 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Kalkschutz-1-500x500.png 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Kalkschutz-1.png 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Kalkschutz-1.png 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Kalkschutz-1.png 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Kalkschutz-1.png\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"561\" height=\"561\">\n                                                                              <span title=\"Traitement anti-calcaire\">\n                            Traitement anti-calcaire                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item \"\n                          >\n                                                      <img data-magnify=\"\" data-glass-img=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Hoehe-1.png\" data-popup-src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Hoehe-1.png\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Hoehe-1-250x250.png 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Hoehe-1-500x500.png 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Hoehe-1.png 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Hoehe-1.png 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Hoehe-1.png 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Hoehe-1.png\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"561\" height=\"561\">\n                                                                              <span title=\"Hauteur\">\n                            Hauteur                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item \"\n                          >\n                                                      <img data-magnify=\"\" data-glass-img=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Glas-1.png\" data-popup-src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Glas-1.png\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Glas-1-250x250.png 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Glas-1-500x500.png 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Glas-1.png 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Glas-1.png 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Glas-1.png 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Glas-1.png\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"561\" height=\"561\">\n                                                                              <span title=\"\u00c9paisseur du verre\">\n                            \u00c9paisseur du verre                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item \"\n                          >\n                                                      <img data-magnify=\"\" data-glass-img=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/express-1.png\" data-popup-src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/express-1.png\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/express-1-250x250.png 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/express-1-500x500.png 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/express-1.png 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/express-1.png 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/express-1.png 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/express-1.png\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"561\" height=\"561\">\n                                                                              <span title=\"Montage expr\u00e8s\">\n                            Montage expr\u00e8s                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item \"\n                          >\n                                                      <img data-magnify=\"\" data-glass-img=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/thermostat-1.png\" data-popup-src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/thermostat-1.png\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/thermostat-1-250x250.png 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/thermostat-1-500x500.png 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/thermostat-1.png 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/thermostat-1.png 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/thermostat-1.png 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/thermostat-1.png\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"561\" height=\"561\">\n                                                                              <span title=\"Thermostat\">\n                            Thermostat                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item \"\n                          >\n                                                      <img data-magnify=\"\" data-glass-img=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/rutschfest6-1-1.png\" data-popup-src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/rutschfest6-1-1.png\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/rutschfest6-1-1-250x250.png 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/rutschfest6-1-1-500x500.png 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/rutschfest6-1-1.png 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/rutschfest6-1-1.png 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/rutschfest6-1-1.png 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/rutschfest6-1-1.png\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"561\" height=\"561\">\n                                                                              <span title=\"L\u00e9g\u00e8rement antid\u00e9rapant\">\n                            L\u00e9g\u00e8rement antid\u00e9rapant                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item \"\n                          >\n                                                      <img data-magnify=\"\" data-glass-img=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/ohne_silikon-1.png\" data-popup-src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/ohne_silikon-1.png\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/ohne_silikon-1-250x250.png 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/ohne_silikon-1-500x500.png 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/ohne_silikon-1.png 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/ohne_silikon-1.png 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/ohne_silikon-1.png 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/ohne_silikon-1.png\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"561\" height=\"561\">\n                                                                              <span title=\"Montage sans silicone\">\n                            Montage sans silicone                          <\/span>\n                        <\/li>\n                                      <\/ul>\n                <\/div>\n              <\/div>\n                              <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/section>\n\n<section class=\"m-download-file-list  spacing-top--small spacing-bottom--medium\">\n  <div class=\"wrapper\">\n    <div class=\"m-download-file-list__row-wrapper\">\n      <div class=\"m-download-file-list__row \" data-accordion=\"\">\n        <div class=\"m-download-file-list__title\" data-accordion-trigger=\"\">\n          T\u00e9l\u00e9chargements        <\/div>\n\n        <div class=\"m-download-file-list__content\">\n\n\n                                \n          \n          \n          <div class=\"m-download-file-list__content-row\">\n            <div class=\"m-download-file-list__content-name\">\n              Fiche technique            <\/div>\n            <div class=\"m-download-file-list__content-data\">\n              <ul class=\"m-download-list\">\n                                              <\/ul>\n            <\/div>\n          <\/div>\n          \n                                <div class=\"m-download-file-list__content-row\">\n              <div class=\"m-download-file-list__content-name\">\n                Conseils d&#8217;entretien              <\/div>\n              <div class=\"m-download-file-list__content-data\">\n                <ul class=\"m-download-list\">\n                  <li class=\"m-download-list__item\">\n                    <img decoding=\"async\" src=\"https:\/\/kinedo-bad.de\/wp-content\/themes\/kinedo\/img\/icons\/pdf.svg\" alt=\"\">\n\n                    <span class=\"m-download-list__item-title\">\n                      Conseils d&#8217;entretien (dt)                    <\/span>\n\n                    <span class=\"m-download-list__item-size\">\n                      66 KB                    <\/span>\n\n                    <a href=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knpf-pflegehinweise-kinedo-2101.pdf\" class=\"m-download-list__item-link\" target=\"_blank\">\n                      T\u00e9l\u00e9charger                    <\/a>\n                  <\/li>\n                <\/ul>\n              <\/div>\n            <\/div>\n                  <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":163518,"parent":174495,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-180571","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kineprime Glass | Kinedo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/kineprime-glass\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kineprime Glass | Kinedo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/kineprime-glass\/\" \/>\n<meta property=\"og:site_name\" content=\"Kinedo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kinedodeutschland\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-21T16:14:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinedo-komplettdusche-brooklyn-1800x1125.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/produits\\\/douches-completes\\\/kineprime-glass\\\/\",\"url\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/produits\\\/douches-completes\\\/kineprime-glass\\\/\",\"name\":\"Kineprime Glass | Kinedo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/produits\\\/douches-completes\\\/kineprime-glass\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/produits\\\/douches-completes\\\/kineprime-glass\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kinedo-bad.de\\\/wp-content\\\/uploads\\\/kinedo-komplettdusche-brooklyn.jpg\",\"datePublished\":\"2023-02-14T14:54:48+00:00\",\"dateModified\":\"2026-01-21T16:14:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/produits\\\/douches-completes\\\/kineprime-glass\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/produits\\\/douches-completes\\\/kineprime-glass\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/produits\\\/douches-completes\\\/kineprime-glass\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kinedo-bad.de\\\/wp-content\\\/uploads\\\/kinedo-komplettdusche-brooklyn.jpg\",\"contentUrl\":\"https:\\\/\\\/kinedo-bad.de\\\/wp-content\\\/uploads\\\/kinedo-komplettdusche-brooklyn.jpg\",\"width\":4000,\"height\":2250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/produits\\\/douches-completes\\\/kineprime-glass\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Douches compl\u00e8tes\",\"item\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/produits\\\/douches-completes\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Kineprime Glass\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/\",\"name\":\"SFA Sanibroy GmbH\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/#organization\",\"name\":\"SFA Sanibroy GmbH\",\"url\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kinedo-bad.de\\\/wp-content\\\/uploads\\\/kinedo-logo-final.png\",\"contentUrl\":\"https:\\\/\\\/kinedo-bad.de\\\/wp-content\\\/uploads\\\/kinedo-logo-final.png\",\"width\":280,\"height\":114,\"caption\":\"SFA Sanibroy GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kinedodeutschland\",\"https:\\\/\\\/www.instagram.com\\\/kinedo_d_a_ch\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kineprime Glass | Kinedo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/kineprime-glass\/","og_locale":"fr_FR","og_type":"article","og_title":"Kineprime Glass | Kinedo","og_url":"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/kineprime-glass\/","og_site_name":"Kinedo","article_publisher":"https:\/\/www.facebook.com\/kinedodeutschland","article_modified_time":"2026-01-21T16:14:13+00:00","og_image":[{"width":1800,"height":1125,"url":"https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinedo-komplettdusche-brooklyn-1800x1125.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/kineprime-glass\/","url":"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/kineprime-glass\/","name":"Kineprime Glass | Kinedo","isPartOf":{"@id":"https:\/\/kinedo-bad.de\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/kineprime-glass\/#primaryimage"},"image":{"@id":"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/kineprime-glass\/#primaryimage"},"thumbnailUrl":"https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinedo-komplettdusche-brooklyn.jpg","datePublished":"2023-02-14T14:54:48+00:00","dateModified":"2026-01-21T16:14:13+00:00","breadcrumb":{"@id":"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/kineprime-glass\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/kineprime-glass\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/kineprime-glass\/#primaryimage","url":"https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinedo-komplettdusche-brooklyn.jpg","contentUrl":"https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinedo-komplettdusche-brooklyn.jpg","width":4000,"height":2250},{"@type":"BreadcrumbList","@id":"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/kineprime-glass\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/kinedo-bad.de\/fr\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/kinedo-bad.de\/fr\/produits\/"},{"@type":"ListItem","position":3,"name":"Douches compl\u00e8tes","item":"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/"},{"@type":"ListItem","position":4,"name":"Kineprime Glass"}]},{"@type":"WebSite","@id":"https:\/\/kinedo-bad.de\/fr\/#website","url":"https:\/\/kinedo-bad.de\/fr\/","name":"SFA Sanibroy GmbH","description":"","publisher":{"@id":"https:\/\/kinedo-bad.de\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kinedo-bad.de\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/kinedo-bad.de\/fr\/#organization","name":"SFA Sanibroy GmbH","url":"https:\/\/kinedo-bad.de\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kinedo-bad.de\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinedo-logo-final.png","contentUrl":"https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinedo-logo-final.png","width":280,"height":114,"caption":"SFA Sanibroy GmbH"},"image":{"@id":"https:\/\/kinedo-bad.de\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kinedodeutschland","https:\/\/www.instagram.com\/kinedo_d_a_ch\/"]}]}},"_links":{"self":[{"href":"https:\/\/kinedo-bad.de\/fr\/wp-json\/wp\/v2\/pages\/180571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kinedo-bad.de\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kinedo-bad.de\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kinedo-bad.de\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/kinedo-bad.de\/fr\/wp-json\/wp\/v2\/comments?post=180571"}],"version-history":[{"count":5,"href":"https:\/\/kinedo-bad.de\/fr\/wp-json\/wp\/v2\/pages\/180571\/revisions"}],"predecessor-version":[{"id":181351,"href":"https:\/\/kinedo-bad.de\/fr\/wp-json\/wp\/v2\/pages\/180571\/revisions\/181351"}],"up":[{"embeddable":true,"href":"https:\/\/kinedo-bad.de\/fr\/wp-json\/wp\/v2\/pages\/174495"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kinedo-bad.de\/fr\/wp-json\/wp\/v2\/media\/163518"}],"wp:attachment":[{"href":"https:\/\/kinedo-bad.de\/fr\/wp-json\/wp\/v2\/media?parent=180571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}