{"id":174495,"date":"2023-02-14T16:54:52","date_gmt":"2023-02-14T15:54:52","guid":{"rendered":"https:\/\/kinedo1.fokuspokus.dev\/produits\/douches-completes\/"},"modified":"2026-06-05T14:28:04","modified_gmt":"2026-06-05T12:28:04","slug":"douches-completes","status":"publish","type":"page","link":"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/","title":{"rendered":"Douches compl\u00e8tes"},"content":{"rendered":"<div class=\"m-page-hero small reverse\">\n  <div class=\"m-page-hero__background\">\n                      <picture class=\"rocket-no-lazy m-page-hero__background-img\">\n          <source media=\"(min-width: 105em)\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_eden_pendeltuer_120x80.jpg 2000w,\n                        https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_eden_pendeltuer_120x80-1500x643.jpg 1500w,\n                        https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_eden_pendeltuer_120x80-1000x429.jpg 1000w,\n                        https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_eden_pendeltuer_120x80-500x214.jpg 500w,\n                        https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_eden_pendeltuer_120x80-250x107.jpg 250w\">\n          <source srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/komplettduschen_kinedo.jpg 2000w,\n                        https:\/\/kinedo-bad.de\/wp-content\/uploads\/komplettduschen_kinedo-1500x844.jpg 1500w,\n                        https:\/\/kinedo-bad.de\/wp-content\/uploads\/komplettduschen_kinedo-1000x562.jpg 1000w,\n                        https:\/\/kinedo-bad.de\/wp-content\/uploads\/komplettduschen_kinedo-500x281.jpg 500w,\n                        https:\/\/kinedo-bad.de\/wp-content\/uploads\/komplettduschen_kinedo-250x141.jpg 250w\">\n          <img decoding=\"async\" class=\"rocket-no-lazy\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/komplettduschen_kinedo-1500x844.jpg\" alt=\"\">\n        <\/picture>\n            <\/div>\n\n  <div class=\"m-page-hero__content-wrapper\">\n    <div class=\"m-page-hero__content\">\n      <div class=\"wrapper\">\n        \n        \n                    <h1 class=\"m-page-hero__content-title right\" data-count=\"18\" data-text-align=\"\"\"\">\n            Douches compl\u00e8tes          <\/h1>\n\n        \n        <div class=\"m-page-hero__content-text\">\n                      <p>\n              Cabines de douche modernes et confortables en verre de grande qualit\u00e9 avec l\u2019\u00e9quipement complet \u2013 rapides et faciles \u00e0 installer sans impacter l\u2019aspect visuel.            <\/p>\n          \n\n\n          \n\n            \n\n\n                  <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/div>\n\n<section class=\"m-breadcrumb\">\n  <div class=\"wrapper\">\n    <div id=\"breadcrumbs\" class=\"m-breadcrumb__list\"><span><span><a href=\"https:\/\/kinedo-bad.de\/fr\/\">Start<\/a><\/span><\/span><\/div>  <\/div>\n<\/section>\n\n<section class=\"m-tile-list m-tile-list--1-2 spacing-top--medium spacing-bottom--small\" id=\"Produkte\">\n  <div class=\"wrapper\">\n    <div class=\"m-tile-list__title with-text\">\n      <h2 class=\"\">\n        Le programme complet\u00a0: des cabines de douche modernes et confortables avec l\u2019\u00e9quipement complet      <\/h2>\n\n              <div>\n          <aside class=\"wysiwyg\">\n            <p>D\u00e9couvrez l\u2019une des nombreuses cabines de douche esth\u00e9tiques, superbement \u00e9quip\u00e9es ou avec peu de barri\u00e8res, ou concevez votre douche compl\u00e8te exactement selon votre propre conception de l\u2019espace et vos go\u00fbts personnels. <br \/>\r\n<br \/>\r\nPoint important pour les impatients\u00a0: la plupart de nos mod\u00e8les peuvent \u00eatre install\u00e9s de mani\u00e8re professionnelle en un seul jour et sans joints de silicone. Ce qui caract\u00e9rise tous nos mod\u00e8les : des mat\u00e9riaux haut de gamme et un \u00e9quipement de douche complet.<\/p>\n          <\/aside>\n        <\/div>\n          <\/div>\n\n    <div class=\"m-tile-list__list\">\n                    <a href=\"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/kinemagic\/\" target=\"_self\" class=\"m-tile\">\n                <div class=\"m-tile__content\">\n                  <div class=\"m-tile__background\">\n                    <!-- Falls WP Rocket lazy blockt, Klasse so lassen, sonst entfernen -->\n                    <img class=\"rocket-no-lazy\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kinemagic_kalypso_nischenausfuehrung_offener_duschbereich_teilweise_einbettung_mit_klappsitz-1-250x107.jpg 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kinemagic_kalypso_nischenausfuehrung_offener_duschbereich_teilweise_einbettung_mit_klappsitz-1-500x214.jpg 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kinemagic_kalypso_nischenausfuehrung_offener_duschbereich_teilweise_einbettung_mit_klappsitz-1-1000x429.jpg 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kinemagic_kalypso_nischenausfuehrung_offener_duschbereich_teilweise_einbettung_mit_klappsitz-1-1500x643.jpg 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kinemagic_kalypso_nischenausfuehrung_offener_duschbereich_teilweise_einbettung_mit_klappsitz-1.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kinemagic_kalypso_nischenausfuehrung_offener_duschbereich_teilweise_einbettung_mit_klappsitz-1-1000x429.jpg\" alt=\"Abbildung der Komplett-Duschkabine Kinemagic Kalypso mit hohen R\u00fcckw\u00e4nden und Dusch-Klappsitz\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"6000\" height=\"2571\" loading=\"lazy\" decoding=\"async\">\n                  <\/div>\n                  <div class=\"m-tile__title\">\n                    <span class=\"m-tile__title-name\">\n                      Kinemagic                    <\/span>\n                    <span class=\"m-tile__title-more\">\n                      plus                    <\/span>\n                  <\/div>\n                <\/div>\n                                  <div class=\"m-tile__text\">\n                    C\u2019est magique, la baignoire se transforme en douche\u00a0: avec Kinemagic, vous pouvez remplacer facilement votre ancienne baignoire en confortable douche d\u00e9pourvue de barri\u00e8res et ce, en une seule journ\u00e9e, sans n\u00e9cessiter de gros travaux de montage et de transformation.                  <\/div>\n                              <\/a>\n                    <a href=\"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/brooklyn\/\" target=\"_self\" class=\"m-tile\">\n                <div class=\"m-tile__content\">\n                  <div class=\"m-tile__background\">\n                    <!-- Falls WP Rocket lazy blockt, Klasse so lassen, sonst entfernen -->\n                    <img class=\"rocket-no-lazy\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi-brooklyn-factory-110x80-schwarz-1-250x107.jpg 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi-brooklyn-factory-110x80-schwarz-1-500x214.jpg 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi-brooklyn-factory-110x80-schwarz-1-1000x429.jpg 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi-brooklyn-factory-110x80-schwarz-1-1500x643.jpg 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi-brooklyn-factory-110x80-schwarz-1.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi-brooklyn-factory-110x80-schwarz-1-1000x429.jpg\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"4000\" height=\"1714\" loading=\"lazy\" decoding=\"async\">\n                  <\/div>\n                  <div class=\"m-tile__title\">\n                    <span class=\"m-tile__title-name\">\n                      Brooklyn                    <\/span>\n                    <span class=\"m-tile__title-more\">\n                      plus                    <\/span>\n                  <\/div>\n                <\/div>\n                                  <div class=\"m-tile__text\">\n                    Des douches dans un style industriel intemporel. C\u2019est pour cela que la gamme Brooklyn existe. Ces cinq cabines de douche enti\u00e8rement \u00e9quip\u00e9es unissent un design industriel moderne et des \u00e9l\u00e9ments sanitaires de grande qualit\u00e9.                  <\/div>\n                              <\/a>\n                    <a href=\"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/eden\/\" target=\"_self\" class=\"m-tile\">\n                <div class=\"m-tile__content\">\n                  <div class=\"m-tile__background\">\n                    <!-- Falls WP Rocket lazy blockt, Klasse so lassen, sonst entfernen -->\n                    <img class=\"rocket-no-lazy\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_eden_pendeltuer_120x80-250x107.jpg 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_eden_pendeltuer_120x80-500x214.jpg 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_eden_pendeltuer_120x80-1000x429.jpg 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_eden_pendeltuer_120x80-1500x643.jpg 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_eden_pendeltuer_120x80.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_eden_pendeltuer_120x80-1000x429.jpg\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"4100\" height=\"1757\" loading=\"lazy\" decoding=\"async\">\n                  <\/div>\n                  <div class=\"m-tile__title\">\n                    <span class=\"m-tile__title-name\">\n                      Eden                    <\/span>\n                    <span class=\"m-tile__title-more\">\n                      plus                    <\/span>\n                  <\/div>\n                <\/div>\n                                  <div class=\"m-tile__text\">\n                    Les cabines de douche compl\u00e8tes de la gamme Eden vous m\u00e8nent directement au paradis (de la douche). Essayez-les\u00a0!                  <\/div>\n                              <\/a>\n                    <a href=\"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/kineprime-glass\/\" target=\"_self\" class=\"m-tile\">\n                <div class=\"m-tile__content\">\n                  <div class=\"m-tile__background\">\n                    <!-- Falls WP Rocket lazy blockt, Klasse so lassen, sonst entfernen -->\n                    <img class=\"rocket-no-lazy\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kineprime_glass_nischenausfuehrung_mechanische_mischbatterie_drehtuer_100x80-250x107.jpg 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kineprime_glass_nischenausfuehrung_mechanische_mischbatterie_drehtuer_100x80-500x214.jpg 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kineprime_glass_nischenausfuehrung_mechanische_mischbatterie_drehtuer_100x80-1000x429.jpg 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kineprime_glass_nischenausfuehrung_mechanische_mischbatterie_drehtuer_100x80-1500x643.jpg 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kineprime_glass_nischenausfuehrung_mechanische_mischbatterie_drehtuer_100x80.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kineprime_glass_nischenausfuehrung_mechanische_mischbatterie_drehtuer_100x80-1000x429.jpg\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"4100\" height=\"1757\" loading=\"lazy\" decoding=\"async\">\n                  <\/div>\n                  <div class=\"m-tile__title\">\n                    <span class=\"m-tile__title-name\">\n                      Kineprime Glass                     <\/span>\n                    <span class=\"m-tile__title-more\">\n                      plus                    <\/span>\n                  <\/div>\n                <\/div>\n                                  <div class=\"m-tile__text\">\n                    Les cabines de douche Kineprime Glass conf\u00e8rent \u00e0 la salle de bain un confort haut de gamme.                  <\/div>\n                              <\/a>\n                    <a href=\"https:\/\/kinedo-bad.de\/fr\/produkt\/kinedelta\/\" target=\"_self\" class=\"m-tile\">\n                <div class=\"m-tile__content\">\n                  <div class=\"m-tile__background\">\n                    <!-- Falls WP Rocket lazy blockt, Klasse so lassen, sonst entfernen -->\n                    <img class=\"rocket-no-lazy\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kinedelta_tuer_90x90-250x107.jpg 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kinedelta_tuer_90x90-500x214.jpg 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kinedelta_tuer_90x90-1000x429.jpg 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kinedelta_tuer_90x90-1500x643.jpg 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kinedelta_tuer_90x90.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knmi_kinedelta_tuer_90x90-1000x429.jpg\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"2800\" height=\"1200\" loading=\"lazy\" decoding=\"async\">\n                  <\/div>\n                  <div class=\"m-tile__title\">\n                    <span class=\"m-tile__title-name\">\n                      Kinedelta                    <\/span>\n                    <span class=\"m-tile__title-more\">\n                      plus                    <\/span>\n                  <\/div>\n                <\/div>\n                                  <div class=\"m-tile__text\">\n                    La cabine de douche compl\u00e8te et pratique pour les nouvelles installations et un remplacement rapide.                  <\/div>\n                              <\/a>\n          <\/div>\n  <\/div>\n<\/section>\n\n\n<section class=\"m-full-image-slider  spacing-top--small spacing-bottom--medium\" id=\"Galerie\">\n\n  <div class=\"m-full-image-slider__wrapper\">\n    <div class=\"m-full-image-slider__arrows\">\n      <button class=\"m-full-image-slider__arrow prev\" data-gallery-full-slider-prev=\"\">\n      <\/button>\n      <button class=\"m-full-image-slider__arrow next\" data-gallery-full-slider-next=\"\">\n      <\/button>\n    <\/div>\n    <div data-gallery-full-slider=\"\">\n      \n                          \n            \n\n  <div class=\"m-full-image-slider__slide\">\n    <div class=\"img-wrapper\">\n            <div>\n        <div class=\"img-wrapper\" data-bild=\"\/wp-content\/medien\/knmi_kinemagic_royal+_hohe_nischenausf\u00fchrung_thermostat.jpg\">\n          <img decoding=\"async\" data-lazy=\"\/wp-content\/medien\/knmi_kinemagic_royal+_hohe_nischenausf\u00fchrung_thermostat.jpg\" src=\"\/wp-content\/medien\/large\/knmi_kinemagic_royal+_hohe_nischenausf\u00fchrung_thermostat.webp\" alt=\"knmi_kinemagic_royal+_hohe_nischenausf\u00fchrung_thermostat.jpg\" data-bild=\"\/wp-content\/medien\/knmi_kinemagic_royal+_hohe_nischenausf\u00fchrung_thermostat.jpg\" data-ursprung=\"\/wp-content\/medien\/large\/knmi_kinemagic_royal+_hohe_nischenausf\u00fchrung_thermostat.webp\" srcset=\"\/wp-content\/medien\/medium\/knmi_kinemagic_royal+_hohe_nischenausf\u00fchrung_thermostat.webp 250w, \/wp-content\/medien\/large\/knmi_kinemagic_royal+_hohe_nischenausf\u00fchrung_thermostat.webp 500w, \/wp-content\/medien\/knmi_kinemagic_royal+_hohe_nischenausf\u00fchrung_thermostat.jpg 1000w, \/wp-content\/medien\/knmi_kinemagic_royal+_hohe_nischenausf\u00fchrung_thermostat.jpg 2000w\">\n        <\/div>\n      <\/div>\n    <\/div>\n    <div class=\"wrapper\">\n      <div class=\"m-full-image-slider__untertitel\">\n        <div class=\"m-full-image-slider_title\">\n          <h3>Kinemagic Royal+<\/h3>\n        <\/div>\n        <div class=\"wysiwyg\">\n          Kinemagic Royal+ est une superbe solution compl\u00e8te pour toute salle de bains. La cabine de douche comprend le bac de douche pourvu d&#8217;une surface antid\u00e9rapante, une main courante de s\u00e9curit\u00e9 ergonomique, une barre de maintien suppl\u00e9mentaire, un si\u00e8ge de douche relevable et une douchette \u00e0 main magn\u00e9tique, offrant ainsi un plus grand confort et une plus grande s\u00e9curit\u00e9 lors des soins du corps.nnBon \u00e0 savoir\u00a0: des subventions allant jusqu\u2019\u00e0 4\u00a0180\u00a0\u20ac peuvent \u00eatre demand\u00e9es en cas de d\u00e9pendance aupr\u00e8s des caisses d&#8217;assurance d\u00e9pendance pour tous les mod\u00e8les de la gamme Kinemagic. <br \/>\r\n<br \/>\r\nD\u2019autres aides sont disponibles via les programmes de la banque KfW 455-B \u00ab\u00a0R\u00e9novation adapt\u00e9e aux personnes \u00e2g\u00e9es\u00a0\u00bb (jusqu\u2019\u00e0 2\u00a0500\u00a0\u20ac) et \u00ab\u00a0Maison adapt\u00e9e aux personnes \u00e2g\u00e9es\u00a0\u00bb (jusqu\u2019\u00e0 6\u00a0250\u00a0\u20ac).        <\/div>\n\n      <\/div>\n    <\/div>\n  <\/div>\n\n          \n            \n\n  <div class=\"m-full-image-slider__slide\">\n    <div class=\"img-wrapper\">\n            <div>\n        <div class=\"img-wrapper\" data-bild=\"\/wp-content\/medien\/knmi_kinemagic_royal_halbhohe_nischenausf\u00fchrung_thermostat_schiebet\u00fcr_glas_mit_mattiertem_mittelteil.jpg\">\n          <img decoding=\"async\" data-lazy=\"\/wp-content\/medien\/knmi_kinemagic_royal_halbhohe_nischenausf\u00fchrung_thermostat_schiebet\u00fcr_glas_mit_mattiertem_mittelteil.jpg\" src=\"\/wp-content\/medien\/large\/knmi_kinemagic_royal_halbhohe_nischenausf\u00fchrung_thermostat_schiebet\u00fcr_glas_mit_mattiertem_mittelteil.webp\" alt=\"knmi_kinemagic_royal_halbhohe_nischenausf\u00fchrung_thermostat_schiebet\u00fcr_glas_mit_mattiertem_mittelteil.jpg\" data-bild=\"\/wp-content\/medien\/knmi_kinemagic_royal_halbhohe_nischenausf\u00fchrung_thermostat_schiebet\u00fcr_glas_mit_mattiertem_mittelteil.jpg\" data-ursprung=\"\/wp-content\/medien\/large\/knmi_kinemagic_royal_halbhohe_nischenausf\u00fchrung_thermostat_schiebet\u00fcr_glas_mit_mattiertem_mittelteil.webp\" srcset=\"\/wp-content\/medien\/medium\/knmi_kinemagic_royal_halbhohe_nischenausf\u00fchrung_thermostat_schiebet\u00fcr_glas_mit_mattiertem_mittelteil.webp 250w, \/wp-content\/medien\/large\/knmi_kinemagic_royal_halbhohe_nischenausf\u00fchrung_thermostat_schiebet\u00fcr_glas_mit_mattiertem_mittelteil.webp 500w, \/wp-content\/medien\/knmi_kinemagic_royal_halbhohe_nischenausf\u00fchrung_thermostat_schiebet\u00fcr_glas_mit_mattiertem_mittelteil.jpg 1000w, \/wp-content\/medien\/knmi_kinemagic_royal_halbhohe_nischenausf\u00fchrung_thermostat_schiebet\u00fcr_glas_mit_mattiertem_mittelteil.jpg 2000w\">\n        <\/div>\n      <\/div>\n    <\/div>\n    <div class=\"wrapper\">\n      <div class=\"m-full-image-slider__untertitel\">\n        <div class=\"m-full-image-slider_title\">\n          <h3>Kinemagic Royal<\/h3>\n        <\/div>\n        <div class=\"wysiwyg\">\n          Kinemagic Royal est une excellente solution compl\u00e8te pour toutes les salles de bains. La cabine de douche comprend un bac de douche \u00e0 surface antid\u00e9rapante, un si\u00e8ge de douche relevable \u00e0 surface antid\u00e9rapante, deux barres de maintien et une douchette magn\u00e9tique, pour des soins corporels particuli\u00e8rement s\u00fbrs et confortables.<br \/>\r\n<br \/>\r\nBon \u00e0 savoir\u00a0: des subventions allant jusqu\u2019\u00e0 4\u00a0180\u00a0\u20ac peuvent \u00eatre demand\u00e9es en cas de d\u00e9pendance aupr\u00e8s des caisses d&#8217;assurance d\u00e9pendance pour tous les mod\u00e8les de la gamme Kinemagic. D\u2019autres aides sont disponibles via les programmes de la banque KfW 455-B \u00ab\u00a0R\u00e9novation adapt\u00e9e aux personnes \u00e2g\u00e9es\u00a0\u00bb (jusqu\u2019\u00e0 2\u00a0500\u00a0\u20ac) et \u00ab\u00a0Maison adapt\u00e9e aux personnes \u00e2g\u00e9es\u00a0\u00bb (jusqu\u2019\u00e0 6\u00a0250\u00a0\u20ac).<br \/>\r\n        <\/div>\n\n      <\/div>\n    <\/div>\n  <\/div>\n\n          \n            \n\n  <div class=\"m-full-image-slider__slide\">\n    <div class=\"img-wrapper\">\n            <div>\n        <div class=\"img-wrapper\" data-bild=\"\/wp-content\/medien\/knmi_kinemagic_design_gemischte_nischenausf\u00fchrung_schiebet\u00fcr.jpg\">\n          <img decoding=\"async\" data-lazy=\"\/wp-content\/medien\/knmi_kinemagic_design_gemischte_nischenausf\u00fchrung_schiebet\u00fcr.jpg\" src=\"\/wp-content\/medien\/large\/knmi_kinemagic_design_gemischte_nischenausf\u00fchrung_schiebet\u00fcr.webp\" alt=\"knmi_kinemagic_design_gemischte_nischenausf\u00fchrung_schiebet\u00fcr.jpg\" data-bild=\"\/wp-content\/medien\/knmi_kinemagic_design_gemischte_nischenausf\u00fchrung_schiebet\u00fcr.jpg\" data-ursprung=\"\/wp-content\/medien\/large\/knmi_kinemagic_design_gemischte_nischenausf\u00fchrung_schiebet\u00fcr.webp\" srcset=\"\/wp-content\/medien\/medium\/knmi_kinemagic_design_gemischte_nischenausf\u00fchrung_schiebet\u00fcr.webp 250w, \/wp-content\/medien\/large\/knmi_kinemagic_design_gemischte_nischenausf\u00fchrung_schiebet\u00fcr.webp 500w, \/wp-content\/medien\/knmi_kinemagic_design_gemischte_nischenausf\u00fchrung_schiebet\u00fcr.jpg 1000w, \/wp-content\/medien\/knmi_kinemagic_design_gemischte_nischenausf\u00fchrung_schiebet\u00fcr.jpg 2000w\">\n        <\/div>\n      <\/div>\n    <\/div>\n    <div class=\"wrapper\">\n      <div class=\"m-full-image-slider__untertitel\">\n        <div class=\"m-full-image-slider_title\">\n          <h3>Kinemagic Design<\/h3>\n        <\/div>\n        <div class=\"wysiwyg\">\n          Kinemagic Design est une excellente solution compl\u00e8te pour toutes les salles de bains. La cabine de douche proche du sol comprend un bac de douche \u00e0 surface antid\u00e9rapante, des barres de maintien et un ensemble complet de robinetterie, pour une hygi\u00e8ne corporelle confortable et un acc\u00e8s facile.<br \/>\r\n<br \/>\r\nBon \u00e0 savoir\u00a0: des subventions allant jusqu\u2019\u00e0 4\u00a0180\u00a0\u20ac peuvent \u00eatre demand\u00e9es en cas de d\u00e9pendance aupr\u00e8s des caisses d&#8217;assurance d\u00e9pendance pour tous les mod\u00e8les de la gamme Kinemagic. D\u2019autres aides sont disponibles via les programmes de la banque KfW 455-B \u00ab\u00a0R\u00e9novation adapt\u00e9e aux personnes \u00e2g\u00e9es\u00a0\u00bb (jusqu\u2019\u00e0 2\u00a0500\u00a0\u20ac) et \u00ab\u00a0Maison adapt\u00e9e aux personnes \u00e2g\u00e9es\u00a0\u00bb (jusqu\u2019\u00e0 6\u00a0250\u00a0\u20ac).<br \/>\r\n        <\/div>\n\n      <\/div>\n    <\/div>\n  <\/div>\n\n          \n            \n\n  <div class=\"m-full-image-slider__slide\">\n    <div class=\"img-wrapper\">\n            <div>\n        <div class=\"img-wrapper\" data-bild=\"\/wp-content\/medien\/knmi_kinemagic_kalypso_eckausf\u00fchrung_offener_duschbereich_teilweise_einbettung_mit_klappsitz.jpg\">\n          <img decoding=\"async\" data-lazy=\"\/wp-content\/medien\/knmi_kinemagic_kalypso_eckausf\u00fchrung_offener_duschbereich_teilweise_einbettung_mit_klappsitz.jpg\" src=\"\/wp-content\/medien\/large\/knmi_kinemagic_kalypso_eckausf\u00fchrung_offener_duschbereich_teilweise_einbettung_mit_klappsitz.webp\" alt=\"knmi_kinemagic_kalypso_eckausf\u00fchrung_offener_duschbereich_teilweise_einbettung_mit_klappsitz.jpg\" data-bild=\"\/wp-content\/medien\/knmi_kinemagic_kalypso_eckausf\u00fchrung_offener_duschbereich_teilweise_einbettung_mit_klappsitz.jpg\" data-ursprung=\"\/wp-content\/medien\/large\/knmi_kinemagic_kalypso_eckausf\u00fchrung_offener_duschbereich_teilweise_einbettung_mit_klappsitz.webp\" srcset=\"\/wp-content\/medien\/medium\/knmi_kinemagic_kalypso_eckausf\u00fchrung_offener_duschbereich_teilweise_einbettung_mit_klappsitz.webp 250w, \/wp-content\/medien\/large\/knmi_kinemagic_kalypso_eckausf\u00fchrung_offener_duschbereich_teilweise_einbettung_mit_klappsitz.webp 500w, \/wp-content\/medien\/knmi_kinemagic_kalypso_eckausf\u00fchrung_offener_duschbereich_teilweise_einbettung_mit_klappsitz.jpg 1000w, \/wp-content\/medien\/knmi_kinemagic_kalypso_eckausf\u00fchrung_offener_duschbereich_teilweise_einbettung_mit_klappsitz.jpg 2000w\">\n        <\/div>\n      <\/div>\n    <\/div>\n    <div class=\"wrapper\">\n      <div class=\"m-full-image-slider__untertitel\">\n        <div class=\"m-full-image-slider_title\">\n          <h3>Kinemagic Kalypso<\/h3>\n        <\/div>\n        <div class=\"wysiwyg\">\n          Kinemagic Kalypso est une excellente solution compl\u00e8te pour toutes les salles de bains. La cabine de douche proche du sol comprend un bac antid\u00e9rapant, un si\u00e8ge de douche relevable avec une large assise antid\u00e9rapante, une barre de maintien (ces deux \u00e9l\u00e9ments pouvant \u00e9galement \u00eatre install\u00e9s ult\u00e9rieurement) et une douchette \u00e0 main magn\u00e9tique, pour une hygi\u00e8ne corporelle s\u00fbre et confortable.<br \/>\r\n<br \/>\r\nBon \u00e0 savoir\u00a0: des subventions allant jusqu\u2019\u00e0 4\u00a0180\u00a0\u20ac peuvent \u00eatre demand\u00e9es en cas de d\u00e9pendance aupr\u00e8s des caisses d&#8217;assurance d\u00e9pendance pour tous les mod\u00e8les de la gamme Kinemagic. D\u2019autres aides sont disponibles via les programmes de la banque KfW 455-B \u00ab\u00a0R\u00e9novation adapt\u00e9e aux personnes \u00e2g\u00e9es\u00a0\u00bb (jusqu\u2019\u00e0 2\u00a0500\u00a0\u20ac) et \u00ab\u00a0Maison adapt\u00e9e aux personnes \u00e2g\u00e9es\u00a0\u00bb (jusqu\u2019\u00e0 6\u00a0250\u00a0\u20ac).        <\/div>\n\n      <\/div>\n    <\/div>\n  <\/div>\n\n          \n            \n\n  <div class=\"m-full-image-slider__slide\">\n    <div class=\"img-wrapper\">\n            <div>\n        <div class=\"img-wrapper\" data-bild=\"\/wp-content\/medien\/knmi_brooklyn_160x80_wei\u00df.jpg\">\n          <img decoding=\"async\" data-lazy=\"\/wp-content\/medien\/knmi_brooklyn_160x80_wei\u00df.jpg\" src=\"\/wp-content\/medien\/large\/knmi_brooklyn_160x80_wei\u00df.webp\" alt=\"knmi_brooklyn_160x80_wei\u00df.jpg\" data-bild=\"\/wp-content\/medien\/knmi_brooklyn_160x80_wei\u00df.jpg\" data-ursprung=\"\/wp-content\/medien\/large\/knmi_brooklyn_160x80_wei\u00df.webp\" srcset=\"\/wp-content\/medien\/medium\/knmi_brooklyn_160x80_wei\u00df.webp 250w, \/wp-content\/medien\/large\/knmi_brooklyn_160x80_wei\u00df.webp 500w, \/wp-content\/medien\/knmi_brooklyn_160x80_wei\u00df.jpg 1000w, \/wp-content\/medien\/knmi_brooklyn_160x80_wei\u00df.jpg 2000w\">\n        <\/div>\n      <\/div>\n    <\/div>\n    <div class=\"wrapper\">\n      <div class=\"m-full-image-slider__untertitel\">\n        <div class=\"m-full-image-slider_title\">\n          <h3>Brooklyn<\/h3>\n        <\/div>\n        <div class=\"wysiwyg\">\n          Brooklyn est une douche enti\u00e8rement \u00e9quip\u00e9e avec douche, cloisons et robinets assortis au look industriel \u00e9l\u00e9gant.<br \/>\r\n<br \/>\r\nMurs bruts, m\u00e9tal, bois \u2014 la Brooklyn s\u2019int\u00e8gre \u00e0 la perfection dans cet environnement. Mais les carreaux de m\u00e9tro ou en ciment sont aussi bien compl\u00e9mentaires du design simple en chrome et des \u00e9l\u00e9ments gris clair.        <\/div>\n\n      <\/div>\n    <\/div>\n  <\/div>\n\n          \n            \n\n  <div class=\"m-full-image-slider__slide\">\n    <div class=\"img-wrapper\">\n            <div>\n        <div class=\"img-wrapper\" data-bild=\"\/wp-content\/medien\/knmi_brooklyn_c90_schiebet\u00fcren_wei\u00df.jpg\">\n          <img decoding=\"async\" data-lazy=\"\/wp-content\/medien\/knmi_brooklyn_c90_schiebet\u00fcren_wei\u00df.jpg\" src=\"\/wp-content\/medien\/large\/knmi_brooklyn_c90_schiebet\u00fcren_wei\u00df.webp\" alt=\"knmi_brooklyn_c90_schiebet\u00fcren_wei\u00df.jpg\" data-bild=\"\/wp-content\/medien\/knmi_brooklyn_c90_schiebet\u00fcren_wei\u00df.jpg\" data-ursprung=\"\/wp-content\/medien\/large\/knmi_brooklyn_c90_schiebet\u00fcren_wei\u00df.webp\" srcset=\"\/wp-content\/medien\/medium\/knmi_brooklyn_c90_schiebet\u00fcren_wei\u00df.webp 250w, \/wp-content\/medien\/large\/knmi_brooklyn_c90_schiebet\u00fcren_wei\u00df.webp 500w, \/wp-content\/medien\/knmi_brooklyn_c90_schiebet\u00fcren_wei\u00df.jpg 1000w, \/wp-content\/medien\/knmi_brooklyn_c90_schiebet\u00fcren_wei\u00df.jpg 2000w\">\n        <\/div>\n      <\/div>\n    <\/div>\n    <div class=\"wrapper\">\n      <div class=\"m-full-image-slider__untertitel\">\n        <div class=\"m-full-image-slider_title\">\n          <h3>Brooklyn C90<\/h3>\n        <\/div>\n        <div class=\"wysiwyg\">\n          Brooklyn C90 est une douche enti\u00e8rement \u00e9quip\u00e9e avec douche, cloisons et robinets assortis au look industriel \u00e9l\u00e9gant.<br \/>\r\n<br \/>\r\nMurs bruts, m\u00e9tal, bois \u2014 la Brooklyn C90 s\u2019int\u00e8gre \u00e0 la perfection dans cet environnement. Mais les carreaux de m\u00e9tro ou en ciment sont aussi bien compl\u00e9mentaires du design simple en chrome et des \u00e9l\u00e9ments gris clair.        <\/div>\n\n      <\/div>\n    <\/div>\n  <\/div>\n\n          \n            \n\n  <div class=\"m-full-image-slider__slide\">\n    <div class=\"img-wrapper\">\n            <div>\n        <div class=\"img-wrapper\" data-bild=\"\/wp-content\/medien\/knmi_brooklyn_factory_110x80_schwarz.jpg\">\n          <img decoding=\"async\" data-lazy=\"\/wp-content\/medien\/knmi_brooklyn_factory_110x80_schwarz.jpg\" src=\"\/wp-content\/medien\/large\/knmi_brooklyn_factory_110x80_schwarz.webp\" alt=\"knmi_brooklyn_factory_110x80_schwarz.jpg\" data-bild=\"\/wp-content\/medien\/knmi_brooklyn_factory_110x80_schwarz.jpg\" data-ursprung=\"\/wp-content\/medien\/large\/knmi_brooklyn_factory_110x80_schwarz.webp\" srcset=\"\/wp-content\/medien\/medium\/knmi_brooklyn_factory_110x80_schwarz.webp 250w, \/wp-content\/medien\/large\/knmi_brooklyn_factory_110x80_schwarz.webp 500w, \/wp-content\/medien\/knmi_brooklyn_factory_110x80_schwarz.jpg 1000w, \/wp-content\/medien\/knmi_brooklyn_factory_110x80_schwarz.jpg 2000w\">\n        <\/div>\n      <\/div>\n    <\/div>\n    <div class=\"wrapper\">\n      <div class=\"m-full-image-slider__untertitel\">\n        <div class=\"m-full-image-slider_title\">\n          <h3>Brooklyn Factory<\/h3>\n        <\/div>\n        <div class=\"wysiwyg\">\n          Brooklyn Factory est une douche enti\u00e8rement \u00e9quip\u00e9e avec douche, cloisons et robinets assortis au look industriel \u00e9l\u00e9gant.<br \/>\r\n<br \/>\r\nMurs bruts, m\u00e9tal, bois \u2014 la Brooklyn Factory s\u2019int\u00e8gre \u00e0 la perfection dans cet environnement. Mais les carreaux de m\u00e9tro ou en ciment sont aussi bien compl\u00e9mentaires du design simple noir mat.        <\/div>\n\n      <\/div>\n    <\/div>\n  <\/div>\n\n          \n            \n\n  <div class=\"m-full-image-slider__slide\">\n    <div class=\"img-wrapper\">\n            <div>\n        <div class=\"img-wrapper\" data-bild=\"\/wp-content\/medien\/knmi_brooklyn_factory_C90_schwenkt\u00fcr_schwarz.jpg\">\n          <img decoding=\"async\" data-lazy=\"\/wp-content\/medien\/knmi_brooklyn_factory_C90_schwenkt\u00fcr_schwarz.jpg\" src=\"\/wp-content\/medien\/large\/knmi_brooklyn_factory_C90_schwenkt\u00fcr_schwarz.webp\" alt=\"knmi_brooklyn_factory_C90_schwenkt\u00fcr_schwarz.jpg\" data-bild=\"\/wp-content\/medien\/knmi_brooklyn_factory_C90_schwenkt\u00fcr_schwarz.jpg\" data-ursprung=\"\/wp-content\/medien\/large\/knmi_brooklyn_factory_C90_schwenkt\u00fcr_schwarz.webp\" srcset=\"\/wp-content\/medien\/medium\/knmi_brooklyn_factory_C90_schwenkt\u00fcr_schwarz.webp 250w, \/wp-content\/medien\/large\/knmi_brooklyn_factory_C90_schwenkt\u00fcr_schwarz.webp 500w, \/wp-content\/medien\/knmi_brooklyn_factory_C90_schwenkt\u00fcr_schwarz.jpg 1000w, \/wp-content\/medien\/knmi_brooklyn_factory_C90_schwenkt\u00fcr_schwarz.jpg 2000w\">\n        <\/div>\n      <\/div>\n    <\/div>\n    <div class=\"wrapper\">\n      <div class=\"m-full-image-slider__untertitel\">\n        <div class=\"m-full-image-slider_title\">\n          <h3>Brooklyn Factory C90<\/h3>\n        <\/div>\n        <div class=\"wysiwyg\">\n          Brooklyn Factory R90 est une douche enti\u00e8rement \u00e9quip\u00e9e avec douche, cloisons et robinets assortis au look industriel \u00e9l\u00e9gant.<br \/>\r\n<br \/>\r\nMurs bruts, m\u00e9tal, bois \u2014 la Brooklyn Factory R90 s\u2019int\u00e8gre \u00e0 la perfection dans cet environnement. Mais les carreaux de m\u00e9tro ou en ciment sont aussi bien compl\u00e9mentaires du design simple noir mat.        <\/div>\n\n      <\/div>\n    <\/div>\n  <\/div>\n\n          \n            \n\n  <div class=\"m-full-image-slider__slide\">\n    <div class=\"img-wrapper\">\n            <div>\n        <div class=\"img-wrapper\" data-bild=\"\/wp-content\/medien\/knmi_brooklyn_R90_90x90_wei\u00df.jpg\">\n          <img decoding=\"async\" data-lazy=\"\/wp-content\/medien\/knmi_brooklyn_R90_90x90_wei\u00df.jpg\" src=\"\/wp-content\/medien\/large\/knmi_brooklyn_R90_90x90_wei\u00df.webp\" alt=\"knmi_brooklyn_R90_90x90_wei\u00df.jpg\" data-bild=\"\/wp-content\/medien\/knmi_brooklyn_R90_90x90_wei\u00df.jpg\" data-ursprung=\"\/wp-content\/medien\/large\/knmi_brooklyn_R90_90x90_wei\u00df.webp\" srcset=\"\/wp-content\/medien\/medium\/knmi_brooklyn_R90_90x90_wei\u00df.webp 250w, \/wp-content\/medien\/large\/knmi_brooklyn_R90_90x90_wei\u00df.webp 500w, \/wp-content\/medien\/knmi_brooklyn_R90_90x90_wei\u00df.jpg 1000w, \/wp-content\/medien\/knmi_brooklyn_R90_90x90_wei\u00df.jpg 2000w\">\n        <\/div>\n      <\/div>\n    <\/div>\n    <div class=\"wrapper\">\n      <div class=\"m-full-image-slider__untertitel\">\n        <div class=\"m-full-image-slider_title\">\n          <h3>Brooklyn R90<\/h3>\n        <\/div>\n        <div class=\"wysiwyg\">\n          Brooklyn R90 est une douche enti\u00e8rement \u00e9quip\u00e9e avec douche, cloisons et robinets assortis au look industriel \u00e9l\u00e9gant.<br \/>\r\n<br \/>\r\nMurs bruts, m\u00e9tal, bois \u2014 la Brooklyn R90 s\u2019int\u00e8gre \u00e0 la perfection dans cet environnement. Mais les carreaux de m\u00e9tro ou en ciment sont aussi bien compl\u00e9mentaires du design simple en chrome et des \u00e9l\u00e9ments gris clair.        <\/div>\n\n      <\/div>\n    <\/div>\n  <\/div>\n\n          \n            \n\n  <div class=\"m-full-image-slider__slide\">\n    <div class=\"img-wrapper\">\n            <div>\n        <div class=\"img-wrapper\" data-bild=\"\/wp-content\/medien\/knmi_eden_schiebetuer_120x80.jpg\">\n          <img decoding=\"async\" data-lazy=\"\/wp-content\/medien\/knmi_eden_schiebetuer_120x80.jpg\" src=\"\/wp-content\/medien\/large\/knmi_eden_schiebetuer_120x80.webp\" alt=\"knmi_eden_schiebetuer_120x80.jpg\" data-bild=\"\/wp-content\/medien\/knmi_eden_schiebetuer_120x80.jpg\" data-ursprung=\"\/wp-content\/medien\/large\/knmi_eden_schiebetuer_120x80.webp\" srcset=\"\/wp-content\/medien\/medium\/knmi_eden_schiebetuer_120x80.webp 250w, \/wp-content\/medien\/large\/knmi_eden_schiebetuer_120x80.webp 500w, \/wp-content\/medien\/knmi_eden_schiebetuer_120x80.jpg 1000w, \/wp-content\/medien\/knmi_eden_schiebetuer_120x80.jpg 2000w\">\n        <\/div>\n      <\/div>\n    <\/div>\n    <div class=\"wrapper\">\n      <div class=\"m-full-image-slider__untertitel\">\n        <div class=\"m-full-image-slider_title\">\n          <h3>Eden<\/h3>\n        <\/div>\n        <div class=\"wysiwyg\">\n          Enti\u00e8rement \u00e9quip\u00e9e et d&#8217;un prix agr\u00e9able : Eden r\u00e9unit le bac de douche, la cloison et le robinet dans un ensemble harmonieux &#8211; un design intemporel, une fonctionnalit\u00e9 bien pens\u00e9e de bout en bout.<br \/>\r\n<br \/>\r\nQue ce soit pour une nouvelle construction ou pour une mise \u00e0 niveau, Eden s&#8217;int\u00e8gre dans tous les int\u00e9rieurs de salle de bains gr\u00e2ce \u00e0 son look clair &#8211; tout en offrant un confort de douche parfait.        <\/div>\n\n      <\/div>\n    <\/div>\n  <\/div>\n\n          \n            \n\n  <div class=\"m-full-image-slider__slide\">\n    <div class=\"img-wrapper\">\n            <div>\n        <div class=\"img-wrapper\" data-bild=\"\/wp-content\/medien\/knmi_eden_plus_schiebetuer_120x80.jpg\">\n          <img decoding=\"async\" data-lazy=\"\/wp-content\/medien\/knmi_eden_plus_schiebetuer_120x80.jpg\" src=\"\/wp-content\/medien\/large\/knmi_eden_plus_schiebetuer_120x80.webp\" alt=\"knmi_eden_plus_schiebetuer_120x80.jpg\" data-bild=\"\/wp-content\/medien\/knmi_eden_plus_schiebetuer_120x80.jpg\" data-ursprung=\"\/wp-content\/medien\/large\/knmi_eden_plus_schiebetuer_120x80.webp\" srcset=\"\/wp-content\/medien\/medium\/knmi_eden_plus_schiebetuer_120x80.webp 250w, \/wp-content\/medien\/large\/knmi_eden_plus_schiebetuer_120x80.webp 500w, \/wp-content\/medien\/knmi_eden_plus_schiebetuer_120x80.jpg 1000w, \/wp-content\/medien\/knmi_eden_plus_schiebetuer_120x80.jpg 2000w\">\n        <\/div>\n      <\/div>\n    <\/div>\n    <div class=\"wrapper\">\n      <div class=\"m-full-image-slider__untertitel\">\n        <div class=\"m-full-image-slider_title\">\n          <h3>Eden+<\/h3>\n        <\/div>\n        <div class=\"wysiwyg\">\n          Enti\u00e8rement \u00e9quip\u00e9e et d&#8217;un prix agr\u00e9able : Eden+ r\u00e9unit le bac de douche, la cloison et la douche \u00e0 effet pluie dans un ensemble harmonieux &#8211; un design intemporel, une fonctionnalit\u00e9 bien pens\u00e9e de bout en bout.<br \/>\r\n<br \/>\r\nQue ce soit pour une nouvelle construction ou pour une mise \u00e0 niveau, Eden+ s&#8217;int\u00e8gre dans tous les int\u00e9rieurs de salle de bains gr\u00e2ce \u00e0 son look clair &#8211; tout en offrant un confort de douche parfait.        <\/div>\n\n      <\/div>\n    <\/div>\n  <\/div>\n\n          \n            \n\n  <div class=\"m-full-image-slider__slide\">\n    <div class=\"img-wrapper\">\n            <div>\n        <div class=\"img-wrapper\" data-bild=\"\/wp-content\/medien\/knmi_eden_c90.jpg\">\n          <img decoding=\"async\" data-lazy=\"\/wp-content\/medien\/knmi_eden_c90.jpg\" src=\"\/wp-content\/medien\/large\/knmi_eden_c90.webp\" alt=\"knmi_eden_c90.jpg\" data-bild=\"\/wp-content\/medien\/knmi_eden_c90.jpg\" data-ursprung=\"\/wp-content\/medien\/large\/knmi_eden_c90.webp\" srcset=\"\/wp-content\/medien\/medium\/knmi_eden_c90.webp 250w, \/wp-content\/medien\/large\/knmi_eden_c90.webp 500w, \/wp-content\/medien\/knmi_eden_c90.jpg 1000w, \/wp-content\/medien\/knmi_eden_c90.jpg 2000w\">\n        <\/div>\n      <\/div>\n    <\/div>\n    <div class=\"wrapper\">\n      <div class=\"m-full-image-slider__untertitel\">\n        <div class=\"m-full-image-slider_title\">\n          <h3>Eden C80 \/ C90<\/h3>\n        <\/div>\n        <div class=\"wysiwyg\">\n          Enti\u00e8rement \u00e9quip\u00e9e et d&#8217;un prix agr\u00e9able : Eden C80 \/ C90 r\u00e9unit le bac de douche, la cloison et le robinet dans un ensemble harmonieux &#8211; un design intemporel, une fonctionnalit\u00e9 bien pens\u00e9e de bout en bout.<br \/>\r\n<br \/>\r\nQue ce soit pour une nouvelle construction ou pour une mise \u00e0 niveau, Eden C80 \/ C90 s&#8217;int\u00e8gre dans tous les int\u00e9rieurs de salle de bains gr\u00e2ce \u00e0 son look clair &#8211; tout en offrant un confort de douche parfait.        <\/div>\n\n      <\/div>\n    <\/div>\n  <\/div>\n\n          \n            \n\n  <div class=\"m-full-image-slider__slide\">\n    <div class=\"img-wrapper\">\n            <div>\n        <div class=\"img-wrapper\" data-bild=\"\/wp-content\/medien\/knmi_eden_plus_c90.jpg\">\n          <img decoding=\"async\" data-lazy=\"\/wp-content\/medien\/knmi_eden_plus_c90.jpg\" src=\"\/wp-content\/medien\/large\/knmi_eden_plus_c90.webp\" alt=\"knmi_eden_plus_c90.jpg\" data-bild=\"\/wp-content\/medien\/knmi_eden_plus_c90.jpg\" data-ursprung=\"\/wp-content\/medien\/large\/knmi_eden_plus_c90.webp\" srcset=\"\/wp-content\/medien\/medium\/knmi_eden_plus_c90.webp 250w, \/wp-content\/medien\/large\/knmi_eden_plus_c90.webp 500w, \/wp-content\/medien\/knmi_eden_plus_c90.jpg 1000w, \/wp-content\/medien\/knmi_eden_plus_c90.jpg 2000w\">\n        <\/div>\n      <\/div>\n    <\/div>\n    <div class=\"wrapper\">\n      <div class=\"m-full-image-slider__untertitel\">\n        <div class=\"m-full-image-slider_title\">\n          <h3>Eden+ C90<\/h3>\n        <\/div>\n        <div class=\"wysiwyg\">\n          Enti\u00e8rement \u00e9quip\u00e9e et d&#8217;un prix agr\u00e9able : Eden+ C90 r\u00e9unit le bac de douche, la cloison et la douche \u00e0 effet pluie dans un ensemble harmonieux &#8211; un design intemporel, une fonctionnalit\u00e9 bien pens\u00e9e de bout en bout.<br \/>\r\n<br \/>\r\nQue ce soit pour une nouvelle construction ou pour une mise \u00e0 niveau, Eden+ C90 s&#8217;int\u00e8gre dans tous les int\u00e9rieurs de salle de bains gr\u00e2ce \u00e0 son look clair &#8211; tout en offrant un confort de douche parfait.        <\/div>\n\n      <\/div>\n    <\/div>\n  <\/div>\n\n          \n            \n\n  <div class=\"m-full-image-slider__slide\">\n    <div class=\"img-wrapper\">\n            <div>\n        <div class=\"img-wrapper\" data-bild=\"\/wp-content\/medien\/knmi_kineprime_glass_eckausfuehrung_schiebetueren_thermostat_100x80.jpg\">\n          <img decoding=\"async\" data-lazy=\"\/wp-content\/medien\/knmi_kineprime_glass_eckausfuehrung_schiebetueren_thermostat_100x80.jpg\" src=\"\/wp-content\/medien\/large\/knmi_kineprime_glass_eckausfuehrung_schiebetueren_thermostat_100x80.webp\" alt=\"knmi_kineprime_glass_eckausfuehrung_schiebetueren_thermostat_100x80.jpg\" data-bild=\"\/wp-content\/medien\/knmi_kineprime_glass_eckausfuehrung_schiebetueren_thermostat_100x80.jpg\" data-ursprung=\"\/wp-content\/medien\/large\/knmi_kineprime_glass_eckausfuehrung_schiebetueren_thermostat_100x80.webp\" srcset=\"\/wp-content\/medien\/medium\/knmi_kineprime_glass_eckausfuehrung_schiebetueren_thermostat_100x80.webp 250w, \/wp-content\/medien\/large\/knmi_kineprime_glass_eckausfuehrung_schiebetueren_thermostat_100x80.webp 500w, \/wp-content\/medien\/knmi_kineprime_glass_eckausfuehrung_schiebetueren_thermostat_100x80.jpg 1000w, \/wp-content\/medien\/knmi_kineprime_glass_eckausfuehrung_schiebetueren_thermostat_100x80.jpg 2000w\">\n        <\/div>\n      <\/div>\n    <\/div>\n    <div class=\"wrapper\">\n      <div class=\"m-full-image-slider__untertitel\">\n        <div class=\"m-full-image-slider_title\">\n          <h3>Kineprime Glass, ex\u00e9cution d&#8217;angle<\/h3>\n        <\/div>\n        <div class=\"wysiwyg\">\n          Kineprime Glass, ex\u00e9cution d&#8217;angle, est une douche enti\u00e8rement \u00e9quip\u00e9e d\u2019un bac de douche, de cloisons et de robinetteries assortis dans un design simple. Qu\u2019elle soit dot\u00e9e d\u2019une porte battante ou de deux portes coulissantes, Kineprime Glass permet un acc\u00e8s ais\u00e9 \u00e0 la douche et un gain de place dans la salle de bains.<br \/>\r\n<br \/>\r\nGr\u00e2ce \u00e0 ses profil\u00e9s blanc mat et \u00e0 son design r\u00e9duit, Kineprime Glass peut \u00eatre combin\u00e9 avec diff\u00e9rents styles d\u2019am\u00e9nagement et ce, en restant discr\u00e8tement \u00e0 l\u2019arri\u00e8re-plan.<br \/>\r\n<br \/>\r\nLa fonctionnalit\u00e9 n&#8217;a pas \u00e9t\u00e9 n\u00e9glig\u00e9e pour autant\u00a0!        <\/div>\n\n      <\/div>\n    <\/div>\n  <\/div>\n\n          \n            \n\n  <div class=\"m-full-image-slider__slide\">\n    <div class=\"img-wrapper\">\n            <div>\n        <div class=\"img-wrapper\" data-bild=\"\/wp-content\/medien\/knmi_kineprime_glass_nischenausfuehrung_schwenktuer_mechanische_mischbatterie_100x80.jpg\">\n          <img decoding=\"async\" data-lazy=\"\/wp-content\/medien\/knmi_kineprime_glass_nischenausfuehrung_schwenktuer_mechanische_mischbatterie_100x80.jpg\" src=\"\/wp-content\/medien\/large\/knmi_kineprime_glass_nischenausfuehrung_schwenktuer_mechanische_mischbatterie_100x80.webp\" alt=\"knmi_kineprime_glass_nischenausfuehrung_schwenktuer_mechanische_mischbatterie_100x80.jpg\" data-bild=\"\/wp-content\/medien\/knmi_kineprime_glass_nischenausfuehrung_schwenktuer_mechanische_mischbatterie_100x80.jpg\" data-ursprung=\"\/wp-content\/medien\/large\/knmi_kineprime_glass_nischenausfuehrung_schwenktuer_mechanische_mischbatterie_100x80.webp\" srcset=\"\/wp-content\/medien\/medium\/knmi_kineprime_glass_nischenausfuehrung_schwenktuer_mechanische_mischbatterie_100x80.webp 250w, \/wp-content\/medien\/large\/knmi_kineprime_glass_nischenausfuehrung_schwenktuer_mechanische_mischbatterie_100x80.webp 500w, \/wp-content\/medien\/knmi_kineprime_glass_nischenausfuehrung_schwenktuer_mechanische_mischbatterie_100x80.jpg 1000w, \/wp-content\/medien\/knmi_kineprime_glass_nischenausfuehrung_schwenktuer_mechanische_mischbatterie_100x80.jpg 2000w\">\n        <\/div>\n      <\/div>\n    <\/div>\n    <div class=\"wrapper\">\n      <div class=\"m-full-image-slider__untertitel\">\n        <div class=\"m-full-image-slider_title\">\n          <h3>Kineprime Glass, ex\u00e9cution en niche<\/h3>\n        <\/div>\n        <div class=\"wysiwyg\">\n          Kineprime Glass, ex\u00e9cution en niche, est une douche enti\u00e8rement \u00e9quip\u00e9e d\u2019un bac de douche, de cloisons et de robinetteries assortis dans un design simple. La porte battante permet un acc\u00e8s ais\u00e9 \u00e0 la douche et un gain de place dans la salle de bains.<br \/>\r\n<br \/>\r\nGr\u00e2ce \u00e0 ses profil\u00e9s blanc mat et \u00e0 son design r\u00e9duit, Kineprime Glass peut \u00eatre combin\u00e9 avec diff\u00e9rents styles d\u2019am\u00e9nagement et ce, en restant discr\u00e8tement \u00e0 l\u2019arri\u00e8re-plan.<br \/>\r\n<br \/>\r\nLa fonctionnalit\u00e9 n&#8217;a pas \u00e9t\u00e9 n\u00e9glig\u00e9e pour autant\u00a0!        <\/div>\n\n      <\/div>\n    <\/div>\n  <\/div>\n\n          \n            \n\n  <div class=\"m-full-image-slider__slide\">\n    <div class=\"img-wrapper\">\n            <div>\n        <div class=\"img-wrapper\" data-bild=\"\/wp-content\/medien\/knmi_kinedelta_t\u00fcr_90x90.jpg\">\n          <img decoding=\"async\" data-lazy=\"\/wp-content\/medien\/knmi_kinedelta_t\u00fcr_90x90.jpg\" src=\"\/wp-content\/medien\/large\/knmi_kinedelta_t\u00fcr_90x90.webp\" alt=\"knmi_kinedelta_t\u00fcr_90x90.jpg\" data-bild=\"\/wp-content\/medien\/knmi_kinedelta_t\u00fcr_90x90.jpg\" data-ursprung=\"\/wp-content\/medien\/large\/knmi_kinedelta_t\u00fcr_90x90.webp\" srcset=\"\/wp-content\/medien\/medium\/knmi_kinedelta_t\u00fcr_90x90.webp 250w, \/wp-content\/medien\/large\/knmi_kinedelta_t\u00fcr_90x90.webp 500w, \/wp-content\/medien\/knmi_kinedelta_t\u00fcr_90x90.jpg 1000w, \/wp-content\/medien\/knmi_kinedelta_t\u00fcr_90x90.jpg 2000w\">\n        <\/div>\n      <\/div>\n    <\/div>\n    <div class=\"wrapper\">\n      <div class=\"m-full-image-slider__untertitel\">\n        <div class=\"m-full-image-slider_title\">\n          <h3>Kinedelta<\/h3>\n        <\/div>\n        <div class=\"wysiwyg\">\n          Vous souhaitez tout d&#8217;abord une cabine de douche compl\u00e8te pratique qui soit en plus facile et rapide \u00e0 installer\u00a0? D\u00e9couvrez alors Kinedelta.        <\/div>\n\n      <\/div>\n    <\/div>\n  <\/div>\n\n                  \n          <\/div>\n  <\/div>\n\n<\/section>\n\n\n\n<section class=\"m-background  \" style=\" background-color: #f6f6f6;\" >\n  <div class=\"acf-innerblocks-container\">\n<!-- Block Big Kachel -->\n<section class=\"m-big-tile-list  spacing-top--medium spacing-bottom--medium\">\n  <div class=\"wrapper\">\n    <div class=\"m-big-tile-list__content\">\n                              \n            <div class=\"m-big-tile\">\n\n\n              <div class=\"m-big-tile__content\">\n                                                    <a class=\"m-big-tile__background\" href=\"https:\/\/kinedo-bad.de\/kinemagic-filter\/\" target=\"_self\">\n\n                    <img srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinemagic-filter-250x180.webp 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinemagic-filter-500x360.webp 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinemagic-filter-1000x719.webp 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinemagic-filter-1500x1079.webp 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinemagic-filter.webp 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinemagic-filter-1000x719.webp\" alt=\"Leicht zug\u00e4ngliche Duschkabine mit zum teilweise mattierter Glasfront in einem hell eingerichteten, teilsanierten Badezimmer.\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"1582\" height=\"1138\">\n                  <\/a>\n\n                \n\n                <div class=\"m-big-tile__title\">\n                  Filtre Kinemagic                <\/div>\n              <\/div>\n              <div class=\"m-big-tile__footer\">\n                <p>\n                  La voie qui vous m\u00e8ne directement \u00e0 la douche compl\u00e8te parfaitement adapt\u00e9e \u00e0 votre salle de bains. Avec le filtre de la gamme Kinemagic, vous trouvez facilement la douche personnelle de vos r\u00eaves, \u00e9galement accessible, incluant bac, cloison, panneaux de douche et de nombreux \u00e9l\u00e9ments de design superbes et visant \u00e0 am\u00e9liorer la s\u00e9curit\u00e9.                  <\/p>\n\n\n                                                    <a class=\"btn fill\" href=\"https:\/\/kinedo-bad.de\/kinemagic-filter\/\" target=\"_self\">\n                     Filtrer maintenant<\/a>\n\n                \n\n              <\/div>\n\n            <\/div>\n\n\n          \n            <div class=\"m-big-tile\">\n\n\n              <div class=\"m-big-tile__content\">\n                                                    <a class=\"m-big-tile__background\" href=\"https:\/\/kinedo-bad.de\/duo-konfigurator\/\" target=\"_self\">\n\n                    <img srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/duo-konfigurator-entwurf-250x148.png 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/duo-konfigurator-entwurf-500x297.png 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/duo-konfigurator-entwurf-1000x594.png 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/duo-konfigurator-entwurf-1500x890.png 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/duo-konfigurator-entwurf.png 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/duo-konfigurator-entwurf-1000x594.png\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1187\">\n                  <\/a>\n\n                \n\n                <div class=\"m-big-tile__title\">\n                  Configurateur DUO                <\/div>\n              <\/div>\n              <div class=\"m-big-tile__footer\">\n                <p>\n                  Douche + baignoire : avec notre baignoire-douche DUO, vous avez les deux en un ! Notre configurateur DUO vous aide \u00e0 choisir et \u00e0 cr\u00e9er le mod\u00e8le de votre choix.                 <\/p>\n\n\n                                                    <a class=\"btn fill\" href=\"https:\/\/kinedo-bad.de\/duo-konfigurator\/\" target=\"_self\">\n                     Configurer maintenant<\/a>\n\n                \n\n              <\/div>\n\n            <\/div>\n\n\n                        \n    <\/div>\n  <\/div>\n<\/section>\n<\/div>\n<\/section>\n\n<section class=\"m-product-color-accordion  spacing-top--medium spacing-bottom--none\">\n  <div class=\"wrapper\">\n    <div class=\"m-product-color-accordion__row-wrapper\">\n      <div class=\"m-product-color-accordion__row open\" data-accordion=\"\">\n        <div class=\"m-product-color-accordion__title\" data-accordion-trigger=\"\">\n          Ex\u00e9cutions, Couleurs, Mat\u00e9riaux, Caract\u00e9ristiques\n        <\/div>\n        <div class=\"m-product-color-accordion__content\">\n\n                                              <div class=\"m-product-color-accordion__content-row\" data-name=\"Ex\u00e9cutions\">\n                <div class=\"m-product-color-accordion__content-name\">\n                  Ex\u00e9cutions                <\/div>\n\n\n\n                <div class=\"m-product-color-accordion__content-data\">\n                  <ul class=\"m-square-list\">\n                                            <li class=\"m-square-list__item \"\n                          >\n                                                      <img  data-popup-src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knw-nischenausfuehrung.svg\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knw-nischenausfuehrung.svg\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\">\n                                                                              <span title=\"Ex\u00e9cution en niche\">\n                            Ex\u00e9cution en niche                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item \"\n                          >\n                                                      <img  data-popup-src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knw-eckausfuehrung.svg\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knw-eckausfuehrung.svg\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\">\n                                                                              <span title=\"Ex\u00e9cution d&#039;angle\">\n                            Ex\u00e9cution d&#039;angle                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item \"\n                          >\n                                                      <img  data-popup-src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knw-wandausfuehrung.svg\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knw-wandausfuehrung.svg\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\">\n                                                                              <span title=\"Ex\u00e9cution murale\">\n                            Ex\u00e9cution murale                          <\/span>\n                        <\/li>\n                                      <\/ul>\n                <\/div>\n              <\/div>\n                                                <div class=\"m-product-color-accordion__content-row\" data-name=\"Couleurs\">\n                <div class=\"m-product-color-accordion__content-name\">\n                  Couleurs                <\/div>\n\n\n\n                <div class=\"m-product-color-accordion__content-data\">\n                  <ul class=\"m-square-list\">\n                                            <li class=\"m-square-list__item m-img-magnifier-glass\"\n                          data-productname=\"Kinedelta\">\n                                                      <img data-magnify=\"\" data-glass-img=\"\/wp-content\/medien\/large\/knw_weiss.webp\" data-popup-src=\"\/wp-content\/medien\/knw_weiss.jpg\" srcset=\"\/wp-content\/medien\/small\/knw_weiss.webp 250w, \/wp-content\/medien\/medium\/knw_weiss.webp 500w, \/wp-content\/medien\/large\/knw_weiss.webp 1000w, \/wp-content\/medien\/knw_weiss.jpg 1500w, \/wp-content\/medien\/knw_weiss.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"\/wp-content\/medien\/large\/knw_weiss.webp\" alt=\"knw_weiss.jpg\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"2250\">\n                                                                              <span title=\"blanc\">\n                            blanc                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item m-img-magnifier-glass\"\n                          data-productname=\"Brooklyn R90\">\n                                                      <img data-magnify=\"\" data-glass-img=\"\/wp-content\/medien\/large\/knw_brooklyn_hellgrau_und_chrom.webp\" data-popup-src=\"\/wp-content\/medien\/knw_brooklyn_hellgrau_und_chrom.jpg\" srcset=\"\/wp-content\/medien\/small\/knw_brooklyn_hellgrau_und_chrom.webp 250w, \/wp-content\/medien\/medium\/knw_brooklyn_hellgrau_und_chrom.webp 500w, \/wp-content\/medien\/large\/knw_brooklyn_hellgrau_und_chrom.webp 1000w, \/wp-content\/medien\/knw_brooklyn_hellgrau_und_chrom.jpg 1500w, \/wp-content\/medien\/knw_brooklyn_hellgrau_und_chrom.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"\/wp-content\/medien\/large\/knw_brooklyn_hellgrau_und_chrom.webp\" alt=\"knw_brooklyn_hellgrau_und_chrom.jpg\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"4200\" height=\"4200\">\n                                                                              <span title=\"gris clair + chrome\">\n                            gris clair + chrome                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item m-img-magnifier-glass\"\n                          data-productname=\"Brooklyn Factory C90\">\n                                                      <img data-magnify=\"\" data-glass-img=\"\/wp-content\/medien\/large\/knw_schwarz_matt.webp\" data-popup-src=\"\/wp-content\/medien\/knw_schwarz_matt.jpg\" srcset=\"\/wp-content\/medien\/small\/knw_schwarz_matt.webp 250w, \/wp-content\/medien\/medium\/knw_schwarz_matt.webp 500w, \/wp-content\/medien\/large\/knw_schwarz_matt.webp 1000w, \/wp-content\/medien\/knw_schwarz_matt.jpg 1500w, \/wp-content\/medien\/knw_schwarz_matt.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"\/wp-content\/medien\/large\/knw_schwarz_matt.webp\" alt=\"knw_schwarz_matt.jpg\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\">\n                                                                              <span title=\"noir (mat)\">\n                            noir (mat)                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item m-img-magnifier-glass\"\n                          data-productname=\"Kinemagic Kalypso\">\n                                                      <img data-magnify=\"\" data-glass-img=\"\/wp-content\/medien\/large\/knw_chrom.webp\" data-popup-src=\"\/wp-content\/medien\/knw_chrom.jpg\" srcset=\"\/wp-content\/medien\/small\/knw_chrom.webp 250w, \/wp-content\/medien\/medium\/knw_chrom.webp 500w, \/wp-content\/medien\/large\/knw_chrom.webp 1000w, \/wp-content\/medien\/knw_chrom.jpg 1500w, \/wp-content\/medien\/knw_chrom.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"\/wp-content\/medien\/large\/knw_chrom.webp\" alt=\"knw_chrom.jpg\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"2250\">\n                                                                              <span title=\"chrome\">\n                            chrome                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item m-img-magnifier-glass\"\n                          data-productname=\"Kinemagic Design\">\n                                                      <img data-magnify=\"\" data-glass-img=\"\/wp-content\/medien\/large\/knw_hellgrau.webp\" data-popup-src=\"\/wp-content\/medien\/knw_hellgrau.jpg\" srcset=\"\/wp-content\/medien\/small\/knw_hellgrau.webp 250w, \/wp-content\/medien\/medium\/knw_hellgrau.webp 500w, \/wp-content\/medien\/large\/knw_hellgrau.webp 1000w, \/wp-content\/medien\/knw_hellgrau.jpg 1500w, \/wp-content\/medien\/knw_hellgrau.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"\/wp-content\/medien\/large\/knw_hellgrau.webp\" alt=\"knw_hellgrau.jpg\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"2250\">\n                                                                              <span title=\"gris clair rev\u00eatu par poudre\">\n                            gris clair rev\u00eatu par poudre                          <\/span>\n                        <\/li>\n                                      <\/ul>\n                <\/div>\n              <\/div>\n                                                <div class=\"m-product-color-accordion__content-row\" data-name=\"Mat\u00e9riel\">\n                <div class=\"m-product-color-accordion__content-name\">\n                  Mat\u00e9riaux                <\/div>\n\n\n\n                <div class=\"m-product-color-accordion__content-data\">\n                  <ul class=\"m-square-list\">\n                                            <li class=\"m-square-list__item m-img-magnifier-glass\"\n                          data-productname=\"Kinedelta\">\n                                                      <img data-magnify=\"\" data-glass-img=\"\/wp-content\/medien\/large\/knw_weiss.webp\" data-popup-src=\"\/wp-content\/medien\/knw_weiss.jpg\" srcset=\"\/wp-content\/medien\/small\/knw_weiss.webp 250w, \/wp-content\/medien\/medium\/knw_weiss.webp 500w, \/wp-content\/medien\/large\/knw_weiss.webp 1000w, \/wp-content\/medien\/knw_weiss.jpg 1500w, \/wp-content\/medien\/knw_weiss.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"\/wp-content\/medien\/large\/knw_weiss.webp\" alt=\"knw_weiss.jpg\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"2250\">\n                                                                              <span title=\"Acrylique, blanc\">\n                            Acrylique, blanc                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item m-img-magnifier-glass\"\n                          data-productname=\"Brooklyn R90\">\n                                                      <img data-magnify=\"\" data-glass-img=\"\/wp-content\/medien\/large\/knw_brooklyn_hellgrau_und_chrom.webp\" data-popup-src=\"\/wp-content\/medien\/knw_brooklyn_hellgrau_und_chrom.jpg\" srcset=\"\/wp-content\/medien\/small\/knw_brooklyn_hellgrau_und_chrom.webp 250w, \/wp-content\/medien\/medium\/knw_brooklyn_hellgrau_und_chrom.webp 500w, \/wp-content\/medien\/large\/knw_brooklyn_hellgrau_und_chrom.webp 1000w, \/wp-content\/medien\/knw_brooklyn_hellgrau_und_chrom.jpg 1500w, \/wp-content\/medien\/knw_brooklyn_hellgrau_und_chrom.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"\/wp-content\/medien\/large\/knw_brooklyn_hellgrau_und_chrom.webp\" alt=\"knw_brooklyn_hellgrau_und_chrom.jpg\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"4200\" height=\"4200\">\n                                                                              <span title=\"Aluminium chrom\u00e9 + peinture en poudre gris clair\">\n                            Aluminium chrom\u00e9 + peinture en poudre gris clair                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item m-img-magnifier-glass\"\n                          data-productname=\"Brooklyn Factory C90\">\n                                                      <img data-magnify=\"\" data-glass-img=\"\/wp-content\/medien\/large\/knw_aluminium_schwarz_pulverbeschichtet.webp\" data-popup-src=\"\/wp-content\/medien\/knw_aluminium_schwarz_pulverbeschichtet.jpg\" srcset=\"\/wp-content\/medien\/small\/knw_aluminium_schwarz_pulverbeschichtet.webp 250w, \/wp-content\/medien\/medium\/knw_aluminium_schwarz_pulverbeschichtet.webp 500w, \/wp-content\/medien\/large\/knw_aluminium_schwarz_pulverbeschichtet.webp 1000w, \/wp-content\/medien\/knw_aluminium_schwarz_pulverbeschichtet.jpg 1500w, \/wp-content\/medien\/knw_aluminium_schwarz_pulverbeschichtet.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"\/wp-content\/medien\/large\/knw_aluminium_schwarz_pulverbeschichtet.webp\" alt=\"knw_aluminium_schwarz_pulverbeschichtet.jpg\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\">\n                                                                              <span title=\"Aluminium, noir rev\u00eatu par poudre\">\n                            Aluminium, noir rev\u00eatu par poudre                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item m-img-magnifier-glass\"\n                          data-productname=\"Kinemagic Kalypso\">\n                                                      <img data-magnify=\"\" data-glass-img=\"\/wp-content\/medien\/large\/knw_chrom.webp\" data-popup-src=\"\/wp-content\/medien\/knw_chrom.jpg\" srcset=\"\/wp-content\/medien\/small\/knw_chrom.webp 250w, \/wp-content\/medien\/medium\/knw_chrom.webp 500w, \/wp-content\/medien\/large\/knw_chrom.webp 1000w, \/wp-content\/medien\/knw_chrom.jpg 1500w, \/wp-content\/medien\/knw_chrom.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"\/wp-content\/medien\/large\/knw_chrom.webp\" alt=\"knw_chrom.jpg\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"2250\">\n                                                                              <span title=\"Aluminium, chrom\u00e9\">\n                            Aluminium, chrom\u00e9                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item m-img-magnifier-glass\"\n                          data-productname=\"Kinemagic Design\">\n                                                      <img data-magnify=\"\" data-glass-img=\"\/wp-content\/medien\/large\/knw_hellgrau.webp\" data-popup-src=\"\/wp-content\/medien\/knw_hellgrau.jpg\" srcset=\"\/wp-content\/medien\/small\/knw_hellgrau.webp 250w, \/wp-content\/medien\/medium\/knw_hellgrau.webp 500w, \/wp-content\/medien\/large\/knw_hellgrau.webp 1000w, \/wp-content\/medien\/knw_hellgrau.jpg 1500w, \/wp-content\/medien\/knw_hellgrau.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"\/wp-content\/medien\/large\/knw_hellgrau.webp\" alt=\"knw_hellgrau.jpg\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"2250\">\n                                                                              <span title=\"Aluminium, gris clair rev\u00eatu par poudre\">\n                            Aluminium, gris clair rev\u00eatu par poudre                          <\/span>\n                        <\/li>\n                                      <\/ul>\n                <\/div>\n              <\/div>\n                                                <div class=\"m-product-color-accordion__content-row\" data-name=\"Mat\u00e9riau verre\">\n                <div class=\"m-product-color-accordion__content-name\">\n                  Mat\u00e9riau verre                <\/div>\n\n\n\n                <div class=\"m-product-color-accordion__content-data\">\n                  <ul class=\"m-square-list\">\n                                            <li class=\"m-square-list__item m-img-magnifier-glass\"\n                          data-productname=\"Kinedelta\">\n                                                      <img data-magnify=\"\" data-glass-img=\"\/wp-content\/medien\/large\/knw_deltaglas.webp\" data-popup-src=\"\/wp-content\/medien\/knw_deltaglas.jpg\" srcset=\"\/wp-content\/medien\/small\/knw_deltaglas.webp 250w, \/wp-content\/medien\/medium\/knw_deltaglas.webp 500w, \/wp-content\/medien\/large\/knw_deltaglas.webp 1000w, \/wp-content\/medien\/knw_deltaglas.jpg 1500w, \/wp-content\/medien\/knw_deltaglas.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"\/wp-content\/medien\/large\/knw_deltaglas.webp\" alt=\"knw_deltaglas.jpg\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"2250\">\n                                                                              <span title=\"Verre Deltaglas\">\n                            Verre Deltaglas                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item m-img-magnifier-glass\"\n                          data-productname=\"Brooklyn R90\">\n                                                      <img data-magnify=\"\" data-glass-img=\"\/wp-content\/medien\/large\/knw_klarglas.webp\" data-popup-src=\"\/wp-content\/medien\/knw_klarglas.jpg\" srcset=\"\/wp-content\/medien\/small\/knw_klarglas.webp 250w, \/wp-content\/medien\/medium\/knw_klarglas.webp 500w, \/wp-content\/medien\/large\/knw_klarglas.webp 1000w, \/wp-content\/medien\/knw_klarglas.jpg 1500w, \/wp-content\/medien\/knw_klarglas.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"\/wp-content\/medien\/large\/knw_klarglas.webp\" alt=\"knw_klarglas.jpg\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"1042\" height=\"1042\">\n                                                                              <span title=\"Verre transparent\">\n                            Verre transparent                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item m-img-magnifier-glass\"\n                          data-productname=\"Brooklyn Factory C90\">\n                                                      <img data-magnify=\"\" data-glass-img=\"\/wp-content\/medien\/large\/knw_klarglas_mit_siebdruckstreifen_schwarz.webp\" data-popup-src=\"\/wp-content\/medien\/knw_klarglas_mit_siebdruckstreifen_schwarz.jpg\" srcset=\"\/wp-content\/medien\/small\/knw_klarglas_mit_siebdruckstreifen_schwarz.webp 250w, \/wp-content\/medien\/medium\/knw_klarglas_mit_siebdruckstreifen_schwarz.webp 500w, \/wp-content\/medien\/large\/knw_klarglas_mit_siebdruckstreifen_schwarz.webp 1000w, \/wp-content\/medien\/knw_klarglas_mit_siebdruckstreifen_schwarz.jpg 1500w, \/wp-content\/medien\/knw_klarglas_mit_siebdruckstreifen_schwarz.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"\/wp-content\/medien\/large\/knw_klarglas_mit_siebdruckstreifen_schwarz.webp\" alt=\"knw_klarglas_mit_siebdruckstreifen_schwarz.jpg\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"1042\" height=\"1042\">\n                                                                              <span title=\"Verre clair avec bandes s\u00e9rigraphi\u00e9es, noir\">\n                            Verre clair avec bandes s\u00e9rigraphi\u00e9es, noir                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item m-img-magnifier-glass\"\n                          data-productname=\"Kinemagic Kalypso\">\n                                                      <img data-magnify=\"\" data-glass-img=\"\/wp-content\/medien\/large\/knw_klarglas_mit_mattiertem_mittelelement.webp\" data-popup-src=\"\/wp-content\/medien\/knw_klarglas_mit_mattiertem_mittelelement.jpg\" srcset=\"\/wp-content\/medien\/small\/knw_klarglas_mit_mattiertem_mittelelement.webp 250w, \/wp-content\/medien\/medium\/knw_klarglas_mit_mattiertem_mittelelement.webp 500w, \/wp-content\/medien\/large\/knw_klarglas_mit_mattiertem_mittelelement.webp 1000w, \/wp-content\/medien\/knw_klarglas_mit_mattiertem_mittelelement.jpg 1500w, \/wp-content\/medien\/knw_klarglas_mit_mattiertem_mittelelement.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"\/wp-content\/medien\/large\/knw_klarglas_mit_mattiertem_mittelelement.webp\" alt=\"knw_klarglas_mit_mattiertem_mittelelement.jpg\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"1042\" height=\"1042\">\n                                                                              <span title=\"Verre transparent avec \u00e9l\u00e9ment central d\u00e9poli\">\n                            Verre transparent avec \u00e9l\u00e9ment central d\u00e9poli                          <\/span>\n                        <\/li>\n                                      <\/ul>\n                <\/div>\n              <\/div>\n                                                <div class=\"m-product-color-accordion__content-row\" data-name=\"Panneaux muraux\">\n                <div class=\"m-product-color-accordion__content-name\">\n                  Panneaux muraux                <\/div>\n\n\n\n                <div class=\"m-product-color-accordion__content-data\">\n                  <ul class=\"m-square-list\">\n                                            <li class=\"m-square-list__item m-img-magnifier-glass\"\n                          data-productname=\"Kinemagic Kalypso\">\n                                                      <img data-magnify=\"\" data-glass-img=\"\/wp-content\/medien\/large\/knw_weiss.webp\" data-popup-src=\"\/wp-content\/medien\/knw_weiss.jpg\" srcset=\"\/wp-content\/medien\/small\/knw_weiss.webp 250w, \/wp-content\/medien\/medium\/knw_weiss.webp 500w, \/wp-content\/medien\/large\/knw_weiss.webp 1000w, \/wp-content\/medien\/knw_weiss.jpg 1500w, \/wp-content\/medien\/knw_weiss.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"\/wp-content\/medien\/large\/knw_weiss.webp\" alt=\"knw_weiss.jpg\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"2250\">\n                                                                              <span title=\"Verre de s\u00e9curit\u00e9, blanc\">\n                            Verre de s\u00e9curit\u00e9, blanc                          <\/span>\n                        <\/li>\n                                      <\/ul>\n                <\/div>\n              <\/div>\n                                                <div class=\"m-product-color-accordion__content-row\" data-name=\"Receveur de douche\">\n                <div class=\"m-product-color-accordion__content-name\">\n                  Receveur de douche                <\/div>\n\n\n\n                <div class=\"m-product-color-accordion__content-data\">\n                  <ul class=\"m-square-list\">\n                                            <li class=\"m-square-list__item m-img-magnifier-glass\"\n                          data-productname=\"Kinemagic Royal\">\n                                                      <img data-magnify=\"\" data-glass-img=\"\/wp-content\/medien\/large\/knw_biocryl_und_biotec.webp\" data-popup-src=\"\/wp-content\/medien\/knw_biocryl_und_biotec.jpg\" srcset=\"\/wp-content\/medien\/small\/knw_biocryl_und_biotec.webp 250w, \/wp-content\/medien\/medium\/knw_biocryl_und_biotec.webp 500w, \/wp-content\/medien\/large\/knw_biocryl_und_biotec.webp 1000w, \/wp-content\/medien\/knw_biocryl_und_biotec.jpg 1500w, \/wp-content\/medien\/knw_biocryl_und_biotec.jpg 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"\/wp-content\/medien\/large\/knw_biocryl_und_biotec.webp\" alt=\"knw_biocryl_und_biotec.jpg\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\">\n                                                                              <span title=\"Biocryl + Biotec\">\n                            Biocryl + Biotec                          <\/span>\n                        <\/li>\n                                      <\/ul>\n                <\/div>\n              <\/div>\n                                                <div class=\"m-product-color-accordion__content-row\" data-name=\"caract\u00e9ristiques\">\n                <div class=\"m-product-color-accordion__content-name\">\n                  Caract\u00e9ristiques                <\/div>\n\n\n\n                <div class=\"m-product-color-accordion__content-data\">\n                  <ul class=\"m-square-list\">\n                                            <li class=\"m-square-list__item \"\n                          >\n                                                      <img data-magnify=\"\" data-glass-img=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/abmessungen-2.png\" data-popup-src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/abmessungen-2.png\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/abmessungen-2-250x250.png 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/abmessungen-2-500x500.png 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/abmessungen-2.png 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/abmessungen-2.png 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/abmessungen-2.png 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/abmessungen-2.png\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"561\" height=\"561\">\n                                                                              <span title=\"Diff\u00e9rentes dimensions ou adaptations possibles\">\n                            Diff\u00e9rentes dimensions ou adaptations possibles                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item \"\n                          >\n                                                      <img data-magnify=\"\" data-glass-img=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Zugang-1.png\" data-popup-src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Zugang-1.png\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Zugang-1-250x250.png 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Zugang-1-500x500.png 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Zugang-1.png 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Zugang-1.png 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Zugang-1.png 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Zugang-1.png\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"561\" height=\"561\">\n                                                                              <span title=\"Acc\u00e8s ais\u00e9\">\n                            Acc\u00e8s ais\u00e9                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item \"\n                          >\n                                                      <img data-magnify=\"\" data-glass-img=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Kalkschutz-1.png\" data-popup-src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Kalkschutz-1.png\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Kalkschutz-1-250x250.png 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Kalkschutz-1-500x500.png 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Kalkschutz-1.png 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Kalkschutz-1.png 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Kalkschutz-1.png 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Kalkschutz-1.png\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"561\" height=\"561\">\n                                                                              <span title=\"Traitement anti-calcaire\">\n                            Traitement anti-calcaire                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item \"\n                          >\n                                                      <img data-magnify=\"\" data-glass-img=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/einsteighoehe-1.png\" data-popup-src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/einsteighoehe-1.png\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/einsteighoehe-1-250x250.png 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/einsteighoehe-1-500x500.png 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/einsteighoehe-1.png 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/einsteighoehe-1.png 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/einsteighoehe-1.png 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/einsteighoehe-1.png\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"561\" height=\"561\">\n                                                                              <span title=\"Hauteur d\u2019acc\u00e8s\">\n                            Hauteur d\u2019acc\u00e8s                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item \"\n                          >\n                                                      <img data-magnify=\"\" data-glass-img=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Hoehe-1.png\" data-popup-src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Hoehe-1.png\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Hoehe-1-250x250.png 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Hoehe-1-500x500.png 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Hoehe-1.png 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Hoehe-1.png 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Hoehe-1.png 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Hoehe-1.png\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"561\" height=\"561\">\n                                                                              <span title=\"Hauteur\">\n                            Hauteur                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item \"\n                          >\n                                                      <img data-magnify=\"\" data-glass-img=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Glas-1.png\" data-popup-src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Glas-1.png\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Glas-1-250x250.png 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Glas-1-500x500.png 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Glas-1.png 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Glas-1.png 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Glas-1.png 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Glas-1.png\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"561\" height=\"561\">\n                                                                              <span title=\"\u00c9paisseur du verre\">\n                            \u00c9paisseur du verre                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item \"\n                          >\n                                                      <img data-magnify=\"\" data-glass-img=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Glas-1.png\" data-popup-src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Glas-1.png\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Glas-1-250x250.png 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Glas-1-500x500.png 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Glas-1.png 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Glas-1.png 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/Glas-1.png 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/Glas-1.png\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"561\" height=\"561\">\n                                                                              <span title=\"\u00c9paisseur du mat\u00e9riau\">\n                            \u00c9paisseur du mat\u00e9riau                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item \"\n                          >\n                                                      <img data-magnify=\"\" data-glass-img=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/express-1.png\" data-popup-src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/express-1.png\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/express-1-250x250.png 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/express-1-500x500.png 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/express-1.png 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/express-1.png 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/express-1.png 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/express-1.png\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"561\" height=\"561\">\n                                                                              <span title=\"Montage expr\u00e8s\">\n                            Montage expr\u00e8s                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item \"\n                          >\n                                                      <img data-magnify=\"\" data-glass-img=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/thermostat-1.png\" data-popup-src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/thermostat-1.png\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/thermostat-1-250x250.png 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/thermostat-1-500x500.png 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/thermostat-1.png 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/thermostat-1.png 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/thermostat-1.png 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/thermostat-1.png\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"561\" height=\"561\">\n                                                                              <span title=\"Thermostat\">\n                            Thermostat                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item \"\n                          >\n                                                      <img data-magnify=\"\" data-glass-img=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/mischbatterie-1.png\" data-popup-src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/mischbatterie-1.png\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/mischbatterie-1-250x250.png 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/mischbatterie-1-500x500.png 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/mischbatterie-1.png 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/mischbatterie-1.png 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/mischbatterie-1.png 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/mischbatterie-1.png\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"561\" height=\"561\">\n                                                                              <span title=\"Mitigeur m\u00e9canique\">\n                            Mitigeur m\u00e9canique                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item \"\n                          >\n                                                      <img data-magnify=\"\" data-glass-img=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/kopfbrause-1.png\" data-popup-src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/kopfbrause-1.png\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/kopfbrause-1-250x250.png 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/kopfbrause-1-500x500.png 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/kopfbrause-1.png 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/kopfbrause-1.png 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/kopfbrause-1.png 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/kopfbrause-1.png\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"561\" height=\"561\">\n                                                                              <span title=\"Douche de t\u00eate\">\n                            Douche de t\u00eate                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item \"\n                          >\n                                                      <img data-magnify=\"\" data-glass-img=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/foerderfaehig-1.png\" data-popup-src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/foerderfaehig-1.png\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/foerderfaehig-1-250x250.png 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/foerderfaehig-1-500x500.png 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/foerderfaehig-1.png 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/foerderfaehig-1.png 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/foerderfaehig-1.png 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/foerderfaehig-1.png\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"560\">\n                                                                              <span title=\"\u00e9ligible aux aides\">\n                            \u00e9ligible aux aides                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item \"\n                          >\n                                                      <img data-magnify=\"\" data-glass-img=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/rutschfest24-4.png\" data-popup-src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/rutschfest24-4.png\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/rutschfest24-4-250x250.png 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/rutschfest24-4-500x500.png 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/rutschfest24-4.png 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/rutschfest24-4.png 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/rutschfest24-4.png 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/rutschfest24-4.png\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"561\" height=\"561\">\n                                                                              <span title=\"Totalement antid\u00e9rapant\">\n                            Totalement antid\u00e9rapant                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item \"\n                          >\n                                                      <img data-magnify=\"\" data-glass-img=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/rutschfest6-1-1.png\" data-popup-src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/rutschfest6-1-1.png\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/rutschfest6-1-1-250x250.png 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/rutschfest6-1-1-500x500.png 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/rutschfest6-1-1.png 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/rutschfest6-1-1.png 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/rutschfest6-1-1.png 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/rutschfest6-1-1.png\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"561\" height=\"561\">\n                                                                              <span title=\"L\u00e9g\u00e8rement antid\u00e9rapant\">\n                            L\u00e9g\u00e8rement antid\u00e9rapant                          <\/span>\n                        <\/li>\n                                            <li class=\"m-square-list__item \"\n                          >\n                                                      <img data-magnify=\"\" data-glass-img=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/ohne_silikon-1.png\" data-popup-src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/ohne_silikon-1.png\" srcset=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/ohne_silikon-1-250x250.png 250w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/ohne_silikon-1-500x500.png 500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/ohne_silikon-1.png 1000w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/ohne_silikon-1.png 1500w, https:\/\/kinedo-bad.de\/wp-content\/uploads\/ohne_silikon-1.png 2000w\" sizes=\"(min-width: 56em) 950px, 100vw\" src=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/ohne_silikon-1.png\" alt=\"\" itemprop=\"image\" loading=\"lazy\" decoding=\"async\" width=\"561\" height=\"561\">\n                                                                              <span title=\"Montage sans silicone\">\n                            Montage sans silicone                          <\/span>\n                        <\/li>\n                                      <\/ul>\n                <\/div>\n              <\/div>\n                              <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/section>\n\n<section class=\"m-download-file-list  spacing-top--small spacing-bottom--medium\">\n  <div class=\"wrapper\">\n    <div class=\"m-download-file-list__row-wrapper\">\n      <div class=\"m-download-file-list__row \" data-accordion=\"\">\n        <div class=\"m-download-file-list__title\" data-accordion-trigger=\"\">\n          T\u00e9l\u00e9chargements        <\/div>\n\n        <div class=\"m-download-file-list__content\">\n\n\n          \n                                    <div class=\"m-download-file-list__content-row\">\n                <div class=\"m-download-file-list__content-name\">\n                  Brochures                <\/div>\n                <div class=\"m-download-file-list__content-data\">\n                  <ul class=\"m-download-list\">\n                                                                      <li class=\"m-download-list__item\">\n                                                                                                  <img decoding=\"async\" src=\"https:\/\/kinedo-bad.de\/wp-content\/themes\/kinedo\/img\/icons\/pdf-de-file.svg\" alt=\"PDF\" style=\"max-width:28px;max-height:32px;\">\n                                                                <span class=\"m-download-list__item-title\">\n                                  Brochure produit Kinemagic                                <\/span>\n                                <span class=\"m-download-list__item-size\">\n                                  2 MB                                <\/span>\n                                <a href=\"\/wp-content\/medien\/Kinedo_Kinemagic-Broschuere_2405.pdf\" class=\"m-download-list__item-link\" target=\"_blank\">\n                                  T\u00e9l\u00e9charger                                <\/a>\n                              <\/li>\n                                                  <li class=\"m-download-list__item\">\n                                                                                                  <img decoding=\"async\" src=\"https:\/\/kinedo-bad.de\/wp-content\/themes\/kinedo\/img\/icons\/pdf-de-file.svg\" alt=\"PDF\" style=\"max-width:28px;max-height:32px;\">\n                                                                <span class=\"m-download-list__item-title\">\n                                  Information sur la conception de salle de bain accessible                                <\/span>\n                                <span class=\"m-download-list__item-size\">\n                                  3 MB                                <\/span>\n                                <a href=\"\/wp-content\/medien\/Kinedo_Infobroschuere_barrierearme_Badgestaltung.pdf\" class=\"m-download-list__item-link\" target=\"_blank\">\n                                  T\u00e9l\u00e9charger                                <\/a>\n                              <\/li>\n                    \n                  <\/ul>\n                <\/div>\n              <\/div>\n                      \n          \n          <div class=\"m-download-file-list__content-row\">\n            <div class=\"m-download-file-list__content-name\">\n              Fiche technique            <\/div>\n            <div class=\"m-download-file-list__content-data\">\n              <ul class=\"m-download-list\">\n                                                    \n\n                    \n                      \n            <li class=\"m-download-list__item\">\n\n\n                              \n  <img decoding=\"async\" src=\"https:\/\/kinedo-bad.de\/wp-content\/themes\/kinedo\/img\/icons\/pdf-de-file.svg\" alt=\"PDF\" style=\"max-width:28px;max-height:32px;\">\n    \n \n        <span class=\"m-download-list__item-title\">\n                      Kineprime Glass, ex\u00e9cution en niche                  <\/span>\n\n        <span class=\"m-download-list__item-size\">\n          4 MB        <\/span>\n\n        <a href=\"\/wp-content\/medien\/kn_db_2026_Kineprime_nischenausfuehrung.pdf\" class=\"m-download-list__item-link\" target=\"_blank\">\n          T\u00e9l\u00e9charger        <\/a>\n      <\/li>\n      \n                    \n                      \n            <li class=\"m-download-list__item\">\n\n\n                              \n  <img decoding=\"async\" src=\"https:\/\/kinedo-bad.de\/wp-content\/themes\/kinedo\/img\/icons\/pdf-de-file.svg\" alt=\"PDF\" style=\"max-width:28px;max-height:32px;\">\n    \n \n        <span class=\"m-download-list__item-title\">\n                      Eden+                  <\/span>\n\n        <span class=\"m-download-list__item-size\">\n          2 MB        <\/span>\n\n        <a href=\"\/wp-content\/medien\/kn_db_2025_EDEN+_rechteckig.pdf\" class=\"m-download-list__item-link\" target=\"_blank\">\n          T\u00e9l\u00e9charger        <\/a>\n      <\/li>\n      \n                    \n                      \n            <li class=\"m-download-list__item\">\n\n\n                              \n  <img decoding=\"async\" src=\"https:\/\/kinedo-bad.de\/wp-content\/themes\/kinedo\/img\/icons\/pdf-de-file.svg\" alt=\"PDF\" style=\"max-width:28px;max-height:32px;\">\n    \n \n        <span class=\"m-download-list__item-title\">\n                      Eden+ C90                  <\/span>\n\n        <span class=\"m-download-list__item-size\">\n          2 MB        <\/span>\n\n        <a href=\"\/wp-content\/medien\/kn_db_EDEN+_C90.pdf\" class=\"m-download-list__item-link\" target=\"_blank\">\n          T\u00e9l\u00e9charger        <\/a>\n      <\/li>\n      \n                    \n                      \n            <li class=\"m-download-list__item\">\n\n\n                              \n  <img decoding=\"async\" src=\"https:\/\/kinedo-bad.de\/wp-content\/themes\/kinedo\/img\/icons\/pdf-de-file.svg\" alt=\"PDF\" style=\"max-width:28px;max-height:32px;\">\n    \n \n        <span class=\"m-download-list__item-title\">\n                      Eden                  <\/span>\n\n        <span class=\"m-download-list__item-size\">\n          3 MB        <\/span>\n\n        <a href=\"\/wp-content\/medien\/kn_db_2026_EDEN_rechteckig.pdf\" class=\"m-download-list__item-link\" target=\"_blank\">\n          T\u00e9l\u00e9charger        <\/a>\n      <\/li>\n      \n                    \n                      \n            <li class=\"m-download-list__item\">\n\n\n                              \n  <img decoding=\"async\" src=\"https:\/\/kinedo-bad.de\/wp-content\/themes\/kinedo\/img\/icons\/pdf-de-file.svg\" alt=\"PDF\" style=\"max-width:28px;max-height:32px;\">\n    \n \n        <span class=\"m-download-list__item-title\">\n                      Eden C80 \/ C90                  <\/span>\n\n        <span class=\"m-download-list__item-size\">\n          3 MB        <\/span>\n\n        <a href=\"\/wp-content\/medien\/kn_db_2026_EDEN_C80_C90.pdf\" class=\"m-download-list__item-link\" target=\"_blank\">\n          T\u00e9l\u00e9charger        <\/a>\n      <\/li>\n      \n                    \n                      \n            <li class=\"m-download-list__item\">\n\n\n                              \n  <img decoding=\"async\" src=\"https:\/\/kinedo-bad.de\/wp-content\/themes\/kinedo\/img\/icons\/pdf-de-file.svg\" alt=\"PDF\" style=\"max-width:28px;max-height:32px;\">\n    \n \n        <span class=\"m-download-list__item-title\">\n                      Kineprime Glass, ex\u00e9cution d&#8217;angle                  <\/span>\n\n        <span class=\"m-download-list__item-size\">\n          4 MB        <\/span>\n\n        <a href=\"\/wp-content\/medien\/kn_db_2026_kineprime_glass_eckausfuehrung.pdf\" class=\"m-download-list__item-link\" target=\"_blank\">\n          T\u00e9l\u00e9charger        <\/a>\n      <\/li>\n      \n                    \n                      \n            <li class=\"m-download-list__item\">\n\n\n                              \n  <img decoding=\"async\" src=\"https:\/\/kinedo-bad.de\/wp-content\/themes\/kinedo\/img\/icons\/pdf-de-file.svg\" alt=\"PDF\" style=\"max-width:28px;max-height:32px;\">\n    \n \n        <span class=\"m-download-list__item-title\">\n                      Kinemagic Royal+                  <\/span>\n\n        <span class=\"m-download-list__item-size\">\n          7 MB        <\/span>\n\n        <a href=\"\/wp-content\/medien\/kn_db_2026_kinemagic_royal_+.pdf\" class=\"m-download-list__item-link\" target=\"_blank\">\n          T\u00e9l\u00e9charger        <\/a>\n      <\/li>\n      \n                    \n                      \n            <li class=\"m-download-list__item\">\n\n\n                              \n  <img decoding=\"async\" src=\"https:\/\/kinedo-bad.de\/wp-content\/themes\/kinedo\/img\/icons\/pdf-de-file.svg\" alt=\"PDF\" style=\"max-width:28px;max-height:32px;\">\n    \n \n        <span class=\"m-download-list__item-title\">\n                      Kinemagic Royal                  <\/span>\n\n        <span class=\"m-download-list__item-size\">\n          7 MB        <\/span>\n\n        <a href=\"\/wp-content\/medien\/kn_db_2026_kinemagic_royal.pdf\" class=\"m-download-list__item-link\" target=\"_blank\">\n          T\u00e9l\u00e9charger        <\/a>\n      <\/li>\n      \n                    \n                      \n            <li class=\"m-download-list__item\">\n\n\n                              \n  <img decoding=\"async\" src=\"https:\/\/kinedo-bad.de\/wp-content\/themes\/kinedo\/img\/icons\/pdf-de-file.svg\" alt=\"PDF\" style=\"max-width:28px;max-height:32px;\">\n    \n \n        <span class=\"m-download-list__item-title\">\n                      Kinedo Brooklyn Factory                  <\/span>\n\n        <span class=\"m-download-list__item-size\">\n          2 MB        <\/span>\n\n        <a href=\"\/wp-content\/medien\/kn_db_2025_brooklyn_rechteckig.pdf\" class=\"m-download-list__item-link\" target=\"_blank\">\n          T\u00e9l\u00e9charger        <\/a>\n      <\/li>\n            \n                    \n                      \n                  <li class=\"m-download-list__item\">\n\n\n                              \n  <img decoding=\"async\" src=\"https:\/\/kinedo-bad.de\/wp-content\/themes\/kinedo\/img\/icons\/pdf-de-file.svg\" alt=\"PDF\" style=\"max-width:28px;max-height:32px;\">\n    \n \n        <span class=\"m-download-list__item-title\">\n                      Kinedo Kinemagic Design                  <\/span>\n\n        <span class=\"m-download-list__item-size\">\n          8 MB        <\/span>\n\n        <a href=\"\/wp-content\/medien\/kn_db_2026_kinemagic_DESIGN.pdf\" class=\"m-download-list__item-link\" target=\"_blank\">\n          T\u00e9l\u00e9charger        <\/a>\n      <\/li>\n      \n                    \n                      \n            <li class=\"m-download-list__item\">\n\n\n                              \n  <img decoding=\"async\" src=\"https:\/\/kinedo-bad.de\/wp-content\/themes\/kinedo\/img\/icons\/pdf-de-file.svg\" alt=\"PDF\" style=\"max-width:28px;max-height:32px;\">\n    \n \n        <span class=\"m-download-list__item-title\">\n                      Kinedo Brooklyn                  <\/span>\n\n        <span class=\"m-download-list__item-size\">\n          2 MB        <\/span>\n\n        <a href=\"\/wp-content\/medien\/kn_db_2025_brooklyn_rechteckig.pdf\" class=\"m-download-list__item-link\" target=\"_blank\">\n          T\u00e9l\u00e9charger        <\/a>\n      <\/li>\n            \n                    \n                      \n            <li class=\"m-download-list__item\">\n\n\n                              \n  <img decoding=\"async\" src=\"https:\/\/kinedo-bad.de\/wp-content\/themes\/kinedo\/img\/icons\/pdf-de-file.svg\" alt=\"PDF\" style=\"max-width:28px;max-height:32px;\">\n    \n \n        <span class=\"m-download-list__item-title\">\n                      Brooklyn Factory C90                  <\/span>\n\n        <span class=\"m-download-list__item-size\">\n          4 MB        <\/span>\n\n        <a href=\"\/wp-content\/medien\/kn_db_2025_brooklyn_c90.pdf\" class=\"m-download-list__item-link\" target=\"_blank\">\n          T\u00e9l\u00e9charger        <\/a>\n      <\/li>\n      \n                    \n                      \n            <li class=\"m-download-list__item\">\n\n\n                              \n  <img decoding=\"async\" src=\"https:\/\/kinedo-bad.de\/wp-content\/themes\/kinedo\/img\/icons\/pdf-de-file.svg\" alt=\"PDF\" style=\"max-width:28px;max-height:32px;\">\n    \n \n        <span class=\"m-download-list__item-title\">\n                      Kinemagic Kalypso                  <\/span>\n\n        <span class=\"m-download-list__item-size\">\n          6 MB        <\/span>\n\n        <a href=\"\/wp-content\/medien\/kn_db_2026_kinemagic_Kalypso.pdf\" class=\"m-download-list__item-link\" target=\"_blank\">\n          T\u00e9l\u00e9charger        <\/a>\n      <\/li>\n      \n                    \n                      \n            <li class=\"m-download-list__item\">\n\n\n                              \n  <img decoding=\"async\" src=\"https:\/\/kinedo-bad.de\/wp-content\/themes\/kinedo\/img\/icons\/pdf-de-file.svg\" alt=\"PDF\" style=\"max-width:28px;max-height:32px;\">\n    \n \n        <span class=\"m-download-list__item-title\">\n                      Brooklyn C90                  <\/span>\n\n        <span class=\"m-download-list__item-size\">\n          4 MB        <\/span>\n\n        <a href=\"\/wp-content\/medien\/kn_db_2025_brooklyn_c90.pdf\" class=\"m-download-list__item-link\" target=\"_blank\">\n          T\u00e9l\u00e9charger        <\/a>\n      <\/li>\n      \n                    \n                      \n            <li class=\"m-download-list__item\">\n\n\n                              \n  <img decoding=\"async\" src=\"https:\/\/kinedo-bad.de\/wp-content\/themes\/kinedo\/img\/icons\/pdf-de-file.svg\" alt=\"PDF\" style=\"max-width:28px;max-height:32px;\">\n    \n \n        <span class=\"m-download-list__item-title\">\n                      Brooklyn R90                  <\/span>\n\n        <span class=\"m-download-list__item-size\">\n          4 MB        <\/span>\n\n        <a href=\"\/wp-content\/medien\/kn_db_2026_brooklyn_r90.pdf\" class=\"m-download-list__item-link\" target=\"_blank\">\n          T\u00e9l\u00e9charger        <\/a>\n      <\/li>\n      \n                    \n                      \n            <li class=\"m-download-list__item\">\n\n\n                              \n  <img decoding=\"async\" src=\"https:\/\/kinedo-bad.de\/wp-content\/themes\/kinedo\/img\/icons\/pdf-de-file.svg\" alt=\"PDF\" style=\"max-width:28px;max-height:32px;\">\n    \n \n        <span class=\"m-download-list__item-title\">\n                      Kinedo Kinedelta Cabine de douche                  <\/span>\n\n        <span class=\"m-download-list__item-size\">\n          2 MB        <\/span>\n\n        <a href=\"\/wp-content\/medien\/kn_db_2025_kinedelta.pdf\" class=\"m-download-list__item-link\" target=\"_blank\">\n          T\u00e9l\u00e9charger        <\/a>\n      <\/li>\n            \n                                      \n                              <\/ul>\n            <\/div>\n          <\/div>\n          \n                                <div class=\"m-download-file-list__content-row\">\n              <div class=\"m-download-file-list__content-name\">\n                Conseils d&#8217;entretien              <\/div>\n              <div class=\"m-download-file-list__content-data\">\n                <ul class=\"m-download-list\">\n                  <li class=\"m-download-list__item\">\n                    <img decoding=\"async\" src=\"https:\/\/kinedo-bad.de\/wp-content\/themes\/kinedo\/img\/icons\/pdf.svg\" alt=\"\">\n\n                    <span class=\"m-download-list__item-title\">\n                      Conseils d&#8217;entretien (dt)                    <\/span>\n\n                    <span class=\"m-download-list__item-size\">\n                      66 KB                    <\/span>\n\n                    <a href=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/knpf-pflegehinweise-kinedo-2101.pdf\" class=\"m-download-list__item-link\" target=\"_blank\">\n                      T\u00e9l\u00e9charger                    <\/a>\n                  <\/li>\n                <\/ul>\n              <\/div>\n            <\/div>\n                  <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":180125,"parent":174487,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-174495","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Douches compl\u00e8tes | Kinedo<\/title>\n<meta name=\"description\" content=\"Des cabines de douche modernes et confortables et des douches compl\u00e8tes avec du verre de grande qualit\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Douches compl\u00e8tes | Kinedo\" \/>\n<meta property=\"og:description\" content=\"Des cabines de douche modernes et confortables et des douches compl\u00e8tes avec du verre de grande qualit\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/\" \/>\n<meta property=\"og:site_name\" content=\"Kinedo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kinedodeutschland\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-05T12:28:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kinedo-bad.de\/wp-content\/uploads\/komplettduschen_kinedo-1800x1125.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/produits\\\/douches-completes\\\/\",\"url\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/produits\\\/douches-completes\\\/\",\"name\":\"Douches compl\u00e8tes | Kinedo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/produits\\\/douches-completes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/produits\\\/douches-completes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kinedo-bad.de\\\/wp-content\\\/uploads\\\/komplettduschen_kinedo.jpg\",\"datePublished\":\"2023-02-14T15:54:52+00:00\",\"dateModified\":\"2026-06-05T12:28:04+00:00\",\"description\":\"Des cabines de douche modernes et confortables et des douches compl\u00e8tes avec du verre de grande qualit\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/produits\\\/douches-completes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/produits\\\/douches-completes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/produits\\\/douches-completes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kinedo-bad.de\\\/wp-content\\\/uploads\\\/komplettduschen_kinedo.jpg\",\"contentUrl\":\"https:\\\/\\\/kinedo-bad.de\\\/wp-content\\\/uploads\\\/komplettduschen_kinedo.jpg\",\"width\":4100,\"height\":2306},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/produits\\\/douches-completes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Douches compl\u00e8tes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/\",\"name\":\"SFA Sanibroy GmbH\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/#organization\",\"name\":\"SFA Sanibroy GmbH\",\"url\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kinedo-bad.de\\\/wp-content\\\/uploads\\\/kinedo-logo-final.png\",\"contentUrl\":\"https:\\\/\\\/kinedo-bad.de\\\/wp-content\\\/uploads\\\/kinedo-logo-final.png\",\"width\":280,\"height\":114,\"caption\":\"SFA Sanibroy GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/kinedo-bad.de\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kinedodeutschland\",\"https:\\\/\\\/www.instagram.com\\\/kinedo_d_a_ch\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Douches compl\u00e8tes | Kinedo","description":"Des cabines de douche modernes et confortables et des douches compl\u00e8tes avec du verre de grande qualit\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/","og_locale":"fr_FR","og_type":"article","og_title":"Douches compl\u00e8tes | Kinedo","og_description":"Des cabines de douche modernes et confortables et des douches compl\u00e8tes avec du verre de grande qualit\u00e9.","og_url":"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/","og_site_name":"Kinedo","article_publisher":"https:\/\/www.facebook.com\/kinedodeutschland","article_modified_time":"2026-06-05T12:28:04+00:00","og_image":[{"width":1800,"height":1125,"url":"https:\/\/kinedo-bad.de\/wp-content\/uploads\/komplettduschen_kinedo-1800x1125.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/","url":"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/","name":"Douches compl\u00e8tes | Kinedo","isPartOf":{"@id":"https:\/\/kinedo-bad.de\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/#primaryimage"},"image":{"@id":"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/#primaryimage"},"thumbnailUrl":"https:\/\/kinedo-bad.de\/wp-content\/uploads\/komplettduschen_kinedo.jpg","datePublished":"2023-02-14T15:54:52+00:00","dateModified":"2026-06-05T12:28:04+00:00","description":"Des cabines de douche modernes et confortables et des douches compl\u00e8tes avec du verre de grande qualit\u00e9.","breadcrumb":{"@id":"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/#primaryimage","url":"https:\/\/kinedo-bad.de\/wp-content\/uploads\/komplettduschen_kinedo.jpg","contentUrl":"https:\/\/kinedo-bad.de\/wp-content\/uploads\/komplettduschen_kinedo.jpg","width":4100,"height":2306},{"@type":"BreadcrumbList","@id":"https:\/\/kinedo-bad.de\/fr\/produits\/douches-completes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/kinedo-bad.de\/fr\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/kinedo-bad.de\/fr\/produits\/"},{"@type":"ListItem","position":3,"name":"Douches compl\u00e8tes"}]},{"@type":"WebSite","@id":"https:\/\/kinedo-bad.de\/fr\/#website","url":"https:\/\/kinedo-bad.de\/fr\/","name":"SFA Sanibroy GmbH","description":"","publisher":{"@id":"https:\/\/kinedo-bad.de\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kinedo-bad.de\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/kinedo-bad.de\/fr\/#organization","name":"SFA Sanibroy GmbH","url":"https:\/\/kinedo-bad.de\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kinedo-bad.de\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinedo-logo-final.png","contentUrl":"https:\/\/kinedo-bad.de\/wp-content\/uploads\/kinedo-logo-final.png","width":280,"height":114,"caption":"SFA Sanibroy GmbH"},"image":{"@id":"https:\/\/kinedo-bad.de\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kinedodeutschland","https:\/\/www.instagram.com\/kinedo_d_a_ch\/"]}]}},"_links":{"self":[{"href":"https:\/\/kinedo-bad.de\/fr\/wp-json\/wp\/v2\/pages\/174495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kinedo-bad.de\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kinedo-bad.de\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kinedo-bad.de\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/kinedo-bad.de\/fr\/wp-json\/wp\/v2\/comments?post=174495"}],"version-history":[{"count":9,"href":"https:\/\/kinedo-bad.de\/fr\/wp-json\/wp\/v2\/pages\/174495\/revisions"}],"predecessor-version":[{"id":182819,"href":"https:\/\/kinedo-bad.de\/fr\/wp-json\/wp\/v2\/pages\/174495\/revisions\/182819"}],"up":[{"embeddable":true,"href":"https:\/\/kinedo-bad.de\/fr\/wp-json\/wp\/v2\/pages\/174487"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kinedo-bad.de\/fr\/wp-json\/wp\/v2\/media\/180125"}],"wp:attachment":[{"href":"https:\/\/kinedo-bad.de\/fr\/wp-json\/wp\/v2\/media?parent=174495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}